﻿{"id":114758,"date":"2024-11-20T14:02:47","date_gmt":"2024-11-20T13:02:47","guid":{"rendered":"https:\/\/secureus.se\/?post_type=product&#038;p=114758"},"modified":"2026-01-12T12:02:32","modified_gmt":"2026-01-12T11:02:32","slug":"badgemaker-recycled-etiketter-till-namnskylt-40x75","status":"publish","type":"product","link":"https:\/\/secureus.se\/de\/badgemaker-recycled-etiketter-till-namnskylt-40x75\/","title":{"rendered":"BADGEMAKER\u00ae RECYCLED-Etiketten f\u00fcr Namensschild 40\u00d775"},"content":{"rendered":"<p>Gestalten Sie professionelle und dennoch pers\u00f6nliche Namensschilder mit dem kostenlosen Programm DURAPRINT\u00ae, verf\u00fcgbar unter www.duraprint.se. Drucken Sie mit einem Laser- oder Tintenstrahldrucker auf BADGEMAKER\u00ae-Etikettenb\u00f6gen aus 150 Gramm recyceltem PEFC-Papier. Das Namensschild selbst l\u00e4sst sich leicht auseinanderrei\u00dfen. Die Packung mit 20 A4-Bl\u00e4ttern enth\u00e4lt 240 Einstecketiketten mit den Ma\u00dfen 40x75mm (HxB). <\/p>","protected":false},"excerpt":{"rendered":"<p>Etikettenbogen aus recyceltem 150-g-Papier. F\u00fcr Namensschilder im Format 40x75mm. 20 A4-Bl\u00e4tter = 240 Etiketten.<\/p>","protected":false},"featured_media":134659,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4276],"product_tag":[4396],"class_list":{"0":"post-114758","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-etiketter-till-namnskyltar","7":"product_tag-vit","8":"product_shipping_class-tunga-paket","9":"pa_brands-durable","10":"secureus-loop-product","11":"tm-no-options","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product\/114758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media\/134659"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media?parent=114758"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_brand?post=114758"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_cat?post=114758"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_tag?post=114758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}