﻿{"id":148699,"date":"2025-03-12T11:01:46","date_gmt":"2025-03-12T10:01:46","guid":{"rendered":"https:\/\/secureus.se\/dorrstangarsats-ts83-3-6-med-standardarm-brun\/"},"modified":"2026-07-01T10:41:20","modified_gmt":"2026-07-01T08:41:20","slug":"dorrstangarsats-ts83-3-6-med-standardarm-brun","status":"publish","type":"product","link":"https:\/\/secureus.se\/de\/dorrstangarsats-ts83-3-6-med-standardarm-brun\/","title":{"rendered":"Dormakaba TS83 T\u00fcrschlie\u00dfer \u2013 Komplettset \u2013 EN 3-6 \u2013 Standardarm CL\u2011N \u2013 Braun"},"content":{"rendered":"<p><strong>Dormakaba TS83<\/strong> ist ein leistungsstarker und zuverl\u00e4ssiger T\u00fcrschlie\u00dfer f\u00fcr alle, die ein sicheres, sanftes und kontrolliertes Schlie\u00dfen von Innen-, Au\u00dfen- und Brandschutzt\u00fcren ben\u00f6tigen. Dieses Modell wird geliefert als <strong>Komplettset<\/strong> in braun mit <strong>Standardarm CL-N<\/strong>, Dadurch ist es sowohl f\u00fcr Neuinstallationen als auch f\u00fcr Austauschsysteme eine praktische Wahl.<\/p>\n<p>Der T\u00fcrschlie\u00dfer passt <strong>Einzelt\u00fcren bis 1400 mm<\/strong> und hat <strong>stufenlos einstellbare Schlie\u00dfkraft EN 3-6<\/strong>. Es kann montiert werden auf <strong>Scharnierseite des T\u00fcrblatts<\/strong> oder <strong>die Anschlagseite des Rahmens<\/strong> und passt sowohl <strong>linke und rechte T\u00fcren<\/strong>.<\/p>\n<h3>Dies ist im Set enthalten.<\/h3>\n<ul>\n<li>T\u00fcrschlie\u00dfergeh\u00e4use TS83 3-6<\/li>\n<li>Montageplatte 8380<\/li>\n<li>Standardarm CL-N<\/li>\n<\/ul>\n<h3>Eigenschaften<\/h3>\n<ul>\n<li>Komplettes Set mit T\u00fcrschlie\u00dfergeh\u00e4use, Montageplatte und Standardarm<\/li>\n<li>Hydraulischer T\u00fcrschlie\u00dfer mit Druckfeder<\/li>\n<li>Armsystem: <strong>Standardarm<\/strong><\/li>\n<li>Schlie\u00dfkraft: <strong>EINS 3-6<\/strong><\/li>\n<li>Stufenlos einstellbare T\u00fcrschlie\u00dfkraft<\/li>\n<li>Passend f\u00fcr eine einzelne T\u00fcr<\/li>\n<li>Maximale T\u00fcrfl\u00fcgelbreite: <strong>1400 mm<\/strong><\/li>\n<li>Passend f\u00fcr linke und rechte T\u00fcren<\/li>\n<li>Kann an der Scharnierseite des T\u00fcrblatts oder an der Schlie\u00dfblechseite des Rahmens montiert werden.<\/li>\n<li>Maximaler \u00d6ffnungswinkel: <strong>180\u00b0<\/strong><\/li>\n<li>\u00d6ffnungsbremse serienm\u00e4\u00dfig<\/li>\n<li>Oberfl\u00e4chenbehandlung: <strong>Braun<\/strong><\/li>\n<\/ul>\n<h3>Funktionen<\/h3>\n<ul>\n<li>\u00d6ffnungsbremse: Ja<\/li>\n<li>Die Schlie\u00dfgeschwindigkeit ist einstellbar <strong>180\u00b0 bis 0\u00b0<\/strong><\/li>\n<li>Die Aufprallkraft ist einstellbar <strong>7\u00b0 bis 0\u00b0<\/strong><\/li>\n<li>Elektromechanische Konfiguration: Nein<\/li>\n<li>Freischwingfunktion: Nein<\/li>\n<li>Zeitverz\u00f6gerte Schlie\u00dfung: Nein<\/li>\n<\/ul>\n<h3>Messen<\/h3>\n<ul>\n<li>L\u00e4nge: <strong>293 mm<\/strong><\/li>\n<li>H\u00f6he: <strong>60 mm<\/strong><\/li>\n<li>Tiefe: <strong>47,5 mm<\/strong><\/li>\n<\/ul>\n<h3>Geeignet f\u00fcr<\/h3>\n<ul>\n<li>Innent\u00fcren<\/li>\n<li>Vordert\u00fcren<\/li>\n<li>Feuerschutzt\u00fcren<\/li>\n<li>Eingangst\u00fcren<\/li>\n<li>Immobilien, B\u00fcros und \u00f6ffentliche Umgebungen<\/li>\n<\/ul>\n<p>Der Dormakaba TS83 ist eine gute Wahl f\u00fcr alle, die einen suchen <strong>T\u00fcrschlie\u00dfer mit Standardarm<\/strong> Im Komplettset erhalten Sie einen zuverl\u00e4ssigen T\u00fcrschlie\u00dfer mit hoher Einstellbarkeit, stabiler Funktion und einfacher Montage in vielen verschiedenen T\u00fcrumgebungen.<\/p>\n<div style=\"background: #f6f8fa;padding: 14px;border-radius: 6px;margin: 18px 0\"><strong>Ben\u00f6tigen Sie Hilfe bei der Auswahl des richtigen T\u00fcrschlie\u00dfers?<\/strong><br \/>\nVergleichen Sie T\u00fcrtyp, Armtyp und T\u00fcrbreite oder sehen Sie sich weitere Modelle aus unserem Sortiment an.<br \/>\n<a style=\"font-weight: bold\" href=\"https:\/\/secureus.se\/de\/dorrstangare-kompletta\/\"><br \/>\nAlle kompletten T\u00fcrschlie\u00dfer finden Sie hier \u2192<br \/>\n<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p><strong>Dormakaba TS83 T\u00fcrschlie\u00dfer-Komplettset in Braun<\/strong> Mit Standardarm CL-N f\u00fcr sicheres und kontrolliertes Schlie\u00dfen von Innent\u00fcren, Au\u00dfent\u00fcren und Brandschutzt\u00fcren. Passend f\u00fcr <strong>Einzelt\u00fcren bis 1400 mm<\/strong> und kann montiert werden auf <strong>Scharnierseite des T\u00fcrblatts<\/strong> oder <strong>die Anschlagseite des Rahmens<\/strong>.<\/p>\n<p>Das komplette Set beinhaltet: <strong>T\u00fcrschlie\u00dfergeh\u00e4use TS83 3-6, Montageplatte 8380 und Standardarm CL-N<\/strong>. Das Modell hat <strong>stufenlos einstellbare Schlie\u00dfkraft EN 3-6<\/strong>, mit serienm\u00e4\u00dfiger \u00d6ffnungsbremse und passend f\u00fcr links- und rechtsanschlagende T\u00fcren.<\/p>","protected":false},"featured_media":148698,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3258,4864],"product_tag":[4863],"class_list":["post-148699","product","type-product","status-publish","has-post-thumbnail","product_cat-dorrstangare","product_cat-dorrstangare-kompletta","product_tag-pf","pa_brands-dormakaba","secureus-loop-product","tm-no-options","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product\/148699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media\/148698"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media?parent=148699"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_brand?post=148699"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_cat?post=148699"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_tag?post=148699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}