{"id":148952,"date":"2024-12-03T11:31:43","date_gmt":"2024-12-03T10:31:43","guid":{"rendered":"https:\/\/secureus.se\/radionyckel-vaka\/"},"modified":"2026-08-26T22:06:39","modified_gmt":"2026-08-26T20:06:39","slug":"radionyckel-vaka","status":"publish","type":"product","link":"https:\/\/secureus.se\/de\/radionyckel-vaka\/","title":{"rendered":"FUNK-SCHL\u00dcSSELUHR"},"content":{"rendered":"<p>Funkschl\u00fcssel f\u00fcr VAKA C18 und Leser A61 und A66. Der Funkschl\u00fcssel hat eine eindeutige Identit\u00e4t und ist wie ein Tag oder eine Karte mit einer Person im VAKA-System verkn\u00fcpft. Anschlie\u00dfend k\u00f6nnen die Funkschl\u00fcssel ganz einfach zeitgesteuert, gesperrt und f\u00fcr den Zutritt zu verschiedenen T\u00fcren freigegeben werden. Die Kommunikation zwischen den Funkschl\u00fcsseln und C18 erfolgt verschl\u00fcsselt und erm\u00f6glicht eine hohe Abh\u00f6rsicherheit. Vier Tasten mit eindeutigen ID-Codes k\u00f6nnen zur Steuerung verschiedener T\u00fcren\/Relais programmiert werden. Elegantes Design mit einer Schiebeabdeckung, die vor versehentlichem Tastendruck sch\u00fctzt. Reichweite je nach \u00e4u\u00dferen Umst\u00e4nden ca. 5-50 m. Batterie 12V (Typ 27A) im Lieferumfang enthalten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Funkschl\u00fcssel f\u00fcr VAKA C18 und Leser A61 und A66. Der Funkschl\u00fcssel besitzt eine eindeutige Identit\u00e4t und ist im VAKA-System, wie ein Ausweis oder eine Karte, mit einer Person verkn\u00fcpft.<\/p>","protected":false},"featured_media":133378,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3842,1616],"product_tag":[],"class_list":["post-148952","product","type-product","status-publish","has-post-thumbnail","product_cat-axema-vaka-taggar","product_cat-radiosandare-mottagare","pa_brands-axema","secureus-loop-product","tm-no-options","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product\/148952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media\/133378"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media?parent=148952"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_brand?post=148952"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_cat?post=148952"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_tag?post=148952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}