{"id":54437,"date":"2022-06-04T15:31:56","date_gmt":"2022-06-04T13:31:56","guid":{"rendered":"https:\/\/secureus.se\/produkt\/plastkort-med-rfid-mifare4k\/"},"modified":"2026-09-01T16:34:54","modified_gmt":"2026-09-01T14:34:54","slug":"passerkort-rfid-kort-med-rfid-mifare4k","status":"publish","type":"product","link":"https:\/\/secureus.se\/de\/passerkort-rfid-kort-med-rfid-mifare4k\/","title":{"rendered":"Zugangskarte \/ RFID-Karte MIFARE4k Classic\u00ae \u2013 Premium"},"content":{"rendered":"<h1 data-start=\"98\" data-end=\"357\">Zugangskarte \/ RFID-Karte MIFARE4k Classic\u00ae \u2013 Premium<\/h1>\n<p data-start=\"98\" data-end=\"357\">Fachleute <strong data-start=\"113\" data-end=\"162\">Zugangskarte \/ RFID-Karte mit MIFARE 4K Classic\u00ae<\/strong> F\u00fcr Zutrittskontrollsysteme, Besucherverwaltungssysteme, W\u00e4schereibuchungen, Alarmanlagen und andere Sicherheitsl\u00f6sungen. Die Karte entspricht dem Standardformat. <strong data-start=\"280\" data-end=\"288\">CR80<\/strong>, Dadurch ist es mit vielen g\u00e4ngigen Kartenleseger\u00e4ten und Systemen kompatibel.<\/p>\n<p data-start=\"359\" data-end=\"617\">Unsere RFID-Karten werden hergestellt mit <strong data-start=\"389\" data-end=\"421\">hochwertiger Originalchip<\/strong> von anerkannten Herstellern. Es bietet eine zuverl\u00e4ssige, sichere und langfristige L\u00f6sung f\u00fcr Unternehmen, Immobilien, Wohnungseigent\u00fcmergemeinschaften und Betriebe, die stabile Zugangskarten f\u00fcr den t\u00e4glichen Gebrauch ben\u00f6tigen.<\/p>\n<p data-start=\"619\" data-end=\"814\">Die Karte kann bestellt werden bei <strong data-start=\"644\" data-end=\"664\">komplett Ihr eigenes Design<\/strong>, Dazu geh\u00f6ren beispielsweise Logo, Farben, Text, Zahlen oder andere grafische Elemente. Sie erhalten vor der Produktion Korrekturabz\u00fcge, damit die Karten genau Ihren W\u00fcnschen entsprechen.<\/p>\n<h3 data-section-id=\"12qighm\" data-start=\"816\" data-end=\"828\">Vorteile<\/h3>\n<ul data-start=\"830\" data-end=\"1151\">\n<li data-section-id=\"15ud23z\" data-start=\"830\" data-end=\"860\">MIFARE 4K Classic\u00ae RFID-Chip<\/li>\n<li data-section-id=\"1mxy12h\" data-start=\"861\" data-end=\"882\">Standardformat CR80<\/li>\n<li data-section-id=\"r6csho\" data-start=\"883\" data-end=\"947\">Geeignet f\u00fcr Zutrittskontrollsysteme, Alarmanlagen, Besucherinformationssysteme und Buchungssysteme<\/li>\n<li data-section-id=\"15e7vri\" data-start=\"948\" data-end=\"987\">Originalchips von anerkannten Herstellern<\/li>\n<li data-section-id=\"1r1ouk1\" data-start=\"988\" data-end=\"1019\">Kann mit jedem beliebigen Design bedruckt werden<\/li>\n<li data-section-id=\"6dpt6z\" data-start=\"1020\" data-end=\"1063\">M\u00f6glichkeit des Korrekturlesens vor der Produktion<\/li>\n<li data-section-id=\"1u393w1\" data-start=\"1064\" data-end=\"1117\">Professionelles Erscheinungsbild f\u00fcr Unternehmen und Immobilien<\/li>\n<li data-section-id=\"1v78qps\" data-start=\"1118\" data-end=\"1151\">Hohe Qualit\u00e4t und gute Haltbarkeit<\/li>\n<\/ul>\n<p data-start=\"1153\" data-end=\"1307\">Zus\u00e4tzlich zu den im Online-Shop erh\u00e4ltlichen Chips bieten wir bei Bedarf auch weitere RFID-Chips und Sonderl\u00f6sungen an. Dies gilt sowohl f\u00fcr RFID-Karten als auch f\u00fcr andere RFID-Datentr\u00e4ger.<\/p>\n<p data-start=\"1309\" data-end=\"1514\">Ob Sie nur wenige Zugangskarten oder eine gr\u00f6\u00dfere Menge ben\u00f6tigen \u2013 wir helfen Ihnen, die passende L\u00f6sung zu finden. Kontaktieren Sie uns gerne, wenn Sie Beratung zu Kompatibilit\u00e4t, Design oder Chipauswahl ben\u00f6tigen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dieses Produkt verf\u00fcgt \u00fcber einen zertifizierten Chip von NXP\u00ae, einem globalen Technologieunternehmen mit Hauptsitz in Holland. NXP\u00ae ist auf RFID und NFC spezialisiert und bietet eine Reihe von Produkten in den Bereichen Sicherheit, Konnektivit\u00e4t und eingebettete L\u00f6sungen<\/p>","protected":false},"featured_media":144062,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4226,1711],"product_tag":[3077,3073],"class_list":["post-54437","product","type-product","status-publish","has-post-thumbnail","product_cat-rfid-kort-mifare-classic-4k","product_cat-rfid-kort","product_tag-rfid-desfire","product_tag-rfid-mifare4k","pa_brands-stonehouse-security","pa_farg-vit","pa_plastkort-larmsystem-aptus","pa_plastkort-larmsystem-assa-arx-solid-entro","pa_plastkort-larmsystem-axema","pa_plastkort-larmsystem-axema-vaka","pa_plastkort-larmsystem-blank-inga-nummer","pa_plastkort-larmsystem-cdvi","pa_plastkort-larmsystem-decimal-nummer","pa_plastkort-larmsystem-estaka-siffor-valfria","pa_plastkort-larmsystem-hexadecimala-nummer","pa_plastkort-larmsystem-lopnummer-valfria","pa_plastkort-larmsystem-paxton","pa_plastkort-larmsystem-rco","pa_plastkort-larmsystem-tidomat","pa_plastkort-larmsystem-vanderbilt-bewator-entro-8-siffor","pa_plastkort-larmsystem-vanderbilt-bewator-omnis-bewator-2010-13-siffor","pa_plastkort-teknik-mifare4k","secureus-loop-product","tm-has-options","first","instock","sale","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product\/54437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media\/144062"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/media?parent=54437"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_brand?post=54437"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_cat?post=54437"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_tag?post=54437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}