﻿{"id":4834,"count":9,"description":"<h2>Magicard Rio Pro Band<\/h2>\n\n<p>Hier finden Sie Farbb\u00e4nder f\u00fcr Magicard Rio Pro. Diese Kategorie richtet sich an alle, die die passenden Verbrauchsmaterialien f\u00fcr die Rio Pro-Serie suchen und kompatible Produkte einfach finden m\u00f6chten.<\/p>\n\n<p>Falls Sie einen anderen Magicard-Drucker besitzen, gehen Sie bitte zur Kategorie Magicard-Farbb\u00e4nder, um das richtige Modell zu finden.<\/p>","link":"https:\/\/secureus.se\/de\/magicard-rio-pro-ribbons\/","name":"Magicard Rio Pro Band","slug":"magicard-rio-pro-ribbons","taxonomy":"product_cat","parent":3216,"meta":[],"menu_order":113,"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_cat\/4834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product_cat\/3216"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/de\/wp-json\/wp\/v2\/product?product_cat=4834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}