{"id":5262,"count":0,"description":"","link":"https:\/\/secureus.se\/dk\/secureus-update\/","name":"Secureus Update","slug":"secureus-update","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/dk\/wp-json\/wp\/v2\/categories\/5262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/dk\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/secureus.se\/dk\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/dk\/wp-json\/wp\/v2\/posts?categories=5262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}