﻿{"id":138076,"date":"2024-06-12T13:12:58","date_gmt":"2024-06-12T11:12:58","guid":{"rendered":"https:\/\/secureus.se\/?post_type=product&#038;p=138076"},"modified":"2026-07-02T14:30:24","modified_gmt":"2026-07-02T12:30:24","slug":"provkit-solo-23-93-m-rok-vaskor-nedtagare","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/provkit-solo-23-93-m-rok-vaskor-nedtagare\/","title":{"rendered":"Kit de muestra Solo 23 \u2013 9,3 m (humo) \u2013 Bolsas y accesorios desmontables"},"content":{"rendered":"<h1>Kit de muestra Solo 23 \u2013 9,3 m (humo) \u2013 Bolsas y accesorios desmontables<\/h1>\n<h3 data-start=\"319\" data-end=\"380\">Kit de prueba profesional para detectores de humo de hasta 9,3 m<\/h3>\n<p data-start=\"381\" data-end=\"561\">Solo 23 es un kit de prueba eficaz que ofrece una soluci\u00f3n integral para probar y mantener detectores de humo en edificios de gran altura.<\/p>\n<p data-start=\"381\" data-end=\"561\">El kit est\u00e1 dise\u00f1ado para facilitar su manejo, seguridad y transporte.<\/p>\n<h3 data-start=\"563\" data-end=\"587\">Contenido de Solo 23<\/h3>\n<ul data-start=\"588\" data-end=\"1234\">\n<li data-start=\"588\" data-end=\"676\">\n<p data-start=\"590\" data-end=\"676\"><strong data-start=\"590\" data-end=\"618\">Probador de detectores Solo 330<\/strong> \u2013 Prueba de detectores de humo con cilindros de gas de prueba Solo A5.<\/p>\n<\/li>\n<li data-start=\"677\" data-end=\"835\">\n<p data-start=\"679\" data-end=\"835\"><strong data-start=\"679\" data-end=\"705\">P\u00e9rtiga telesc\u00f3pica Solo 100<\/strong> \u2013 largo, 4,5 m con 4 segmentos de fibra de vidrio, se puede combinar con tres postes de extensi\u00f3n Solo 101 para un alcance total de hasta 9,3 m.<\/p>\n<\/li>\n<li data-start=\"836\" data-end=\"913\">\n<p data-start=\"838\" data-end=\"913\"><strong data-start=\"838\" data-end=\"874\">3 \u00d7 varillas de extensi\u00f3n Solo 101<\/strong> \u2013 proporciona m\u00e1xima altura y flexibilidad.<\/p>\n<\/li>\n<li data-start=\"914\" data-end=\"1017\">\n<p data-start=\"916\" data-end=\"1017\"><strong data-start=\"916\" data-end=\"949\">Dispositivo de desmontaje universal Solo 200<\/strong> \u2013 garras ajustables para manejar la mayor\u00eda de los detectores de alarma contra incendios.<\/p>\n<\/li>\n<li data-start=\"1018\" data-end=\"1120\">\n<p data-start=\"1020\" data-end=\"1120\"><strong data-start=\"1020\" data-end=\"1050\">3 cilindros de gas de prueba Solo A5<\/strong> \u2013 optimizado para detectores de humo, suficiente para aproximadamente 400 muestras por botella.<\/p>\n<\/li>\n<li data-start=\"1121\" data-end=\"1234\">\n<p data-start=\"1123\" data-end=\"1234\"><strong data-start=\"1123\" data-end=\"1152\">Estuche de transporte + carcaj Solo 610<\/strong> \u2013 Sistema de almacenamiento pr\u00e1ctico con espacio para varillas, probadores y cilindros de gas de prueba.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1236\" data-end=\"1268\">Uso f\u00e1cil y seguro<\/h3>\n<ol data-start=\"1269\" data-end=\"1536\">\n<li data-start=\"1269\" data-end=\"1328\">\n<p data-start=\"1272\" data-end=\"1328\">Agite las botellas de gas de prueba Solo A5 e inst\u00e1lelas en el Solo 330.<\/p>\n<\/li>\n<li data-start=\"1329\" data-end=\"1373\">\n<p data-start=\"1332\" data-end=\"1373\">Enrosque el recipiente y gire \u00bc de vuelta.<\/p>\n<\/li>\n<li data-start=\"1374\" data-end=\"1456\">\n<p data-start=\"1377\" data-end=\"1456\">Coloque la taza alrededor del detector, presione ligeramente contra el techo y deje que el gas salga.<\/p>\n<\/li>\n<li data-start=\"1457\" data-end=\"1536\">\n<p data-start=\"1460\" data-end=\"1536\">Espere aproximadamente 10 segundos hasta que el detector suene la alarma. Si es necesario, repita la prueba corta.<\/p>\n<\/li>\n<\/ol>\n<h3 data-start=\"1538\" data-end=\"1564\">Ventajas del Solo 23<\/h3>\n<ul data-start=\"1565\" data-end=\"1843\">\n<li data-start=\"1565\" data-end=\"1618\">\n<p data-start=\"1567\" data-end=\"1618\">Equipo completo para probar detectores de humo.<\/p>\n<\/li>\n<li data-start=\"1619\" data-end=\"1682\">\n<p data-start=\"1621\" data-end=\"1682\">Alcance hasta 9,3 m con poste telesc\u00f3pico y extensiones<\/p>\n<\/li>\n<li data-start=\"1683\" data-end=\"1739\">\n<p data-start=\"1685\" data-end=\"1739\">Estuche de transporte profesional y carcaj para un f\u00e1cil transporte.<\/p>\n<\/li>\n<li data-start=\"1740\" data-end=\"1783\">\n<p data-start=\"1742\" data-end=\"1783\">Se adapta a la mayor\u00eda de marcas de detectores.<\/p>\n<\/li>\n<li data-start=\"1784\" data-end=\"1843\">\n<p data-start=\"1786\" data-end=\"1843\">F\u00e1cil manejo y reinicio r\u00e1pido de los detectores.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1845\" data-end=\"1875\">Especificaciones t\u00e9cnicas<\/h3>\n<ul data-start=\"1876\" data-end=\"2163\">\n<li data-start=\"1876\" data-end=\"1909\">\n<p data-start=\"1878\" data-end=\"1909\">Altura de prueba: hasta 9,3 m<\/p>\n<\/li>\n<li data-start=\"1910\" data-end=\"1989\">\n<p data-start=\"1912\" data-end=\"1989\">Contenido: Solo 330, Solo 100, 3 \u00d7 Solo 101, Solo 200, Solo 610, 3 \u00d7 Solo A5<\/p>\n<\/li>\n<li data-start=\"1990\" data-end=\"2052\">\n<p data-start=\"1992\" data-end=\"2052\">Material del poste telesc\u00f3pico: fibra de vidrio, no conductor de electricidad<\/p>\n<\/li>\n<li data-start=\"2053\" data-end=\"2104\">\n<p data-start=\"2055\" data-end=\"2104\">Capacidad de la botella de gas de prueba: aprox. 400 muestras por botella<\/p>\n<\/li>\n<li data-start=\"2105\" data-end=\"2163\">\n<p data-start=\"2107\" data-end=\"2163\">Compatible con: probadores Solo y Testifire, probadores de derribo<\/p>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>El kit de prueba Solo 23 es un kit completo para la comprobaci\u00f3n funcional de detectores de humo de hasta aproximadamente 9,3 m. Incluye la p\u00e9rtiga telesc\u00f3pica Solo 100 con 3 p\u00e9rtigas de extensi\u00f3n Solo 101, el comprobador de detectores Solo 330, el bajante Solo 200, 3 cilindros de gas de prueba Solo A5, y el estuche de transporte y carcaj Solo 610.<\/p>","protected":false},"featured_media":138075,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2945,3849],"product_tag":[],"class_list":["post-138076","product","type-product","status-publish","has-post-thumbnail","product_cat-solo","product_cat-solo-kit","product_shipping_class-tunga-paket","pa_brands-solo","secureus-loop-product","tm-no-options","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/138076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/138075"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=138076"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=138076"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=138076"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=138076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}