﻿{"id":140852,"date":"2023-05-10T09:49:31","date_gmt":"2023-05-10T07:49:31","guid":{"rendered":"https:\/\/secureus.se\/eqqrb-easy-4x10-vit-b100\/"},"modified":"2026-04-23T10:42:58","modified_gmt":"2026-04-23T08:42:58","slug":"eqqrb-easy-4x10-vit-b100","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/eqqrb-easy-4x10-vit-b100\/","title":{"rendered":"EQQRB F\u00c1CIL 4X1.0 BLANCO B100"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cable de se\u00f1al protegido contra llamas y libre de hal\u00f3genos. EQQRB se utiliza como cable de se\u00f1al en diversos sistemas de control y regulaci\u00f3n, incluidos los sistemas de alarma contra incendios. Se coloca en interiores y exteriores. Cumple con los requisitos de resistencia al fuego seg\u00fan CPR clase Dcas2d2a2.<\/p>","protected":false},"featured_media":140851,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2678],"product_tag":[2487],"class_list":{"0":"post-140852","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-telekabel-oskarmad","7":"product_tag-kabel-oskarmad","8":"product_shipping_class-tunga-paket","9":"secureus-loop-product","10":"tm-no-options","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/140852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/140851"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=140852"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=140852"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=140852"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=140852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}