﻿{"id":142129,"date":"2022-07-04T10:41:24","date_gmt":"2022-07-04T08:41:24","guid":{"rendered":"https:\/\/secureus.se\/monteringsstolpe-sa40\/"},"modified":"2026-01-12T13:14:49","modified_gmt":"2026-01-12T12:14:49","slug":"monteringsstolpe-sa40","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/monteringsstolpe-sa40\/","title":{"rendered":"Poste de montaje Safetron SA40"},"content":{"rendered":"<p>Poste de montaje plano de acero inoxidable para placas de cerradura el\u00e9ctricas SAFETRON de la serie est\u00e1ndar: ES17 \/ ES19. Adaptado para el sistema de perfiles SAPA 2050, utilizado junto con cerraduras de caja doble o simple del tipo connect\/evolution o module. <\/p>\n<p>\u2022 Adaptado para SAPA 2050<br \/>\n<br \/>\n\u2022 Correspondiente a ST 4034<br \/>\n<br \/>\n\u2022 Tama\u00f1o de la lengua: 15 mm<br \/>\n<br \/>\n\u2022 Dimensiones: (alto x ancho) 245\u00d736,5 mm<\/p>","protected":false},"excerpt":{"rendered":"<p>Plan monteringsstolpe i rostfritt st\u00e5l f\u00f6r SAFETRON elslutbleck i standardserien: ES17 \/ ES19. Anpassad f\u00f6r SAPA profilsystem 2050, anv\u00e4nds tillsammans med dubbel- eller enkelfall\u00e5s av typen connect\/evolution eller modul. \u2022<\/p>","protected":false},"featured_media":142128,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4735],"product_tag":[4440,4866],"class_list":{"0":"post-142129","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-monteringsstolpe","7":"product_tag-safetron-montagestolpar-es17-es19-sa-modell","8":"product_tag-safetron-20","9":"product_shipping_class-tunga-paket","10":"pa_brands-7safetron","11":"secureus-loop-product","12":"tm-no-options","14":"first","15":"instock","16":"sale","17":"featured","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/142129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/142128"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=142129"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=142129"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=142129"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=142129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}