﻿{"id":164755,"date":"2026-04-22T15:32:19","date_gmt":"2026-04-22T13:32:19","guid":{"rendered":"https:\/\/secureus.se\/evolis-s10252-kortlamineringsmodul-clm-med-lcd-skarm\/"},"modified":"2026-07-02T15:34:38","modified_gmt":"2026-07-02T13:34:38","slug":"evolis-s10252-kortlamineringsmodul-clm-med-lcd-skarm","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/evolis-s10252-kortlamineringsmodul-clm-med-lcd-skarm\/","title":{"rendered":"M\u00f3dulo de laminaci\u00f3n de tarjetas (CLM) Evolis S10252 con pantalla LCD"},"content":{"rendered":"<p>El m\u00f3dulo de laminaci\u00f3n de tarjetas Evolis S10252 (CLM) con pantalla LCD es la soluci\u00f3n perfecta para dar a sus tarjetas un acabado profesional y mayor durabilidad. Gracias a su pantalla LCD intuitiva, podr\u00e1 supervisar y controlar f\u00e1cilmente el proceso de laminaci\u00f3n. Este m\u00f3dulo es compatible con diferentes tama\u00f1os y materiales de tarjetas, lo que lo hace vers\u00e1til y pr\u00e1ctico para diversas necesidades. Proteja sus tarjetas con una capa protectora y un aspecto elegante con el m\u00f3dulo de laminaci\u00f3n de tarjetas Evolis S10252.<\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>M\u00f3dulo de laminaci\u00f3n de tarjetas Evolis S10252 para aplicar superposiciones y pel\u00edculas hologr\u00e1ficas en tarjetas.<\/li>\n<li>Puede utilizarse como unidad independiente o con las impresoras de tarjetas de identificaci\u00f3n Evolis Primacy o Primacy 2.<\/li>\n<li>Configuraci\u00f3n sencilla con interfaz de pantalla LCD<\/li>\n<li>Capacidad de laminaci\u00f3n a doble cara<\/li>\n<li>Se puede conectar directamente a un PC en modo aut\u00f3nomo mediante un cable USB (no incluido).<\/li>\n<li>Compatible con la impresora de tarjetas Evolis Primacy o Primacy 2.<\/li>\n<li>Peso del producto: 0,40 kg<\/li>\n<\/ul>","protected":false},"featured_media":164754,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3205],"product_tag":[],"class_list":["post-164755","product","type-product","status-publish","has-post-thumbnail","product_cat-evolis","product_shipping_class-tunga-paket","pa_brands-evolis","secureus-loop-product","tm-no-options","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/164755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/164754"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=164755"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=164755"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=164755"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=164755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}