﻿{"id":165796,"date":"2024-12-02T15:08:13","date_gmt":"2024-12-02T14:08:13","guid":{"rendered":"https:\/\/secureus.se\/regnskydd-rs-7-i-rostfritt\/"},"modified":"2026-05-12T15:41:19","modified_gmt":"2026-05-12T13:41:19","slug":"regnskydd-rs-7-i-rostfritt","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/regnskydd-rs-7-i-rostfritt\/","title":{"rendered":"FUNDA PARA LLUVIA RS-7 EN ACERO INOXIDABLE"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Recomendado para alargar la vida de su portero autom\u00e1tico, panel de control o tablero de reservas.<br \/>\nFunda de lluvia para PA\/MAP-59 y Vision Light. Fabricado en acero inoxidable.<\/p>","protected":false},"featured_media":165795,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5139,5142],"product_tag":[],"class_list":{"0":"post-165796","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-portapparat-lasare","7":"product_cat-tillbehor-portapparater-lasare","8":"product_shipping_class-tunga-paket","9":"pa_brands-rco","10":"secureus-loop-product","11":"tm-no-options","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/165796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/165795"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=165796"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=165796"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=165796"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=165796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}