﻿{"id":165809,"date":"2024-12-02T14:56:11","date_gmt":"2024-12-02T13:56:11","guid":{"rendered":"https:\/\/secureus.se\/dbl-lasare-nokey-online-s\/"},"modified":"2026-05-12T15:49:46","modified_gmt":"2026-05-12T13:49:46","slug":"dbl-lasare-nokey-online-s","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/dbl-lasare-nokey-online-s\/","title":{"rendered":"LECTOR DOBLE NOKEY ONLINE S"},"content":{"rendered":"<p>El lector de hojas de puerta NoKey Online MIF-508 S se entrega sin teclado, pensado para montaje contra cilindro, con pomo en el interior y apto para puertas con cerraduras m\u00f3dulo\/Connect. El lector cumple con los est\u00e1ndares de cerradura n\u00f3rdicos. La instalaci\u00f3n no da\u00f1a la puerta, sino que se monta utilizando los accesorios disponibles para la fijaci\u00f3n del cilindro est\u00e1ndar y la fijaci\u00f3n de la manija. Dado que todas las conexiones y la mec\u00e1nica se encuentran en el interior de la puerta, la manipulaci\u00f3n y el sabotaje se hacen m\u00e1s dif\u00edciles. \u00a1NOTA! NoKey Gen2 est\u00e1 dise\u00f1ado con un pomo en el interior y debe complementarse con un cilindro en el exterior junto con un anillo de cilindro adecuado de DormaKaba o. HABO, consulte el documento para conocer los anillos de cilindro adecuados. Si no se utiliza NoKey junto con un cilindro, la unidad debe complementarse con un tap\u00f3n de cilindro, E5872211. Si no se utiliza un pomo, el NoKey debe complementarse con un tap\u00f3n de pomo, E5872210. NoKey Gen2 solo est\u00e1 disponible en negro. El lector est\u00e1 completamente integrado en el sistema R-CARD 5000 y se puede utilizar como lector de iniciaci\u00f3n para todos nuestros lectores fuera de l\u00ednea. NoKey Online se ofrece con tecnolog\u00eda de lectura Desfire EV2\/Mifare Classic. Hoja de puerta est\u00e1ndar (espesor m\u00edn.\/m\u00e1x.): 38-80 mm. Hoja de puerta con accesorios (espesor m\u00edn.\/m\u00e1x.): 38-110 mm. Consumo de corriente: nominal 35 mA, m\u00e1ximo 300 mA al abrir\/bloquear a 24 V CC.<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00f6rrbladsl\u00e4sare NoKey Online MIF-508 S levereras utan tangentbord, avsedd f\u00f6r montage mot en cylinder, med vred p\u00e5 insidan och passar till d\u00f6rrar med modul \/ Connect l\u00e5s. L\u00e4saren uppfyller nordisk<\/p>","protected":false},"featured_media":165808,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5141],"product_tag":[],"class_list":{"0":"post-165809","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lasare-passersystem-portapparat-lasare","7":"product_shipping_class-tunga-paket","8":"pa_brands-rco","9":"pa_farg-svart","10":"secureus-loop-product","11":"tm-no-options","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/165809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/165808"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=165809"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=165809"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=165809"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=165809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}