﻿{"id":54527,"date":"2022-05-25T12:22:06","date_gmt":"2022-05-25T10:22:06","guid":{"rendered":"https:\/\/secureus.se\/produkt\/bordslasare-access-mifare-1356-mhz-med-programmerade-systemnummer-v2\/"},"modified":"2026-05-07T15:46:12","modified_gmt":"2026-05-07T13:46:12","slug":"rfid-lasare-access-mifare-1356-mhz-med-programmerade-systemnummer-v2","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/rfid-lasare-access-mifare-1356-mhz-med-programmerade-systemnummer-v2\/","title":{"rendered":"Lector RFID de acceso Mifare \u2013 13,56 MHz programable"},"content":{"rendered":"<p><strong>\u00a1NOTA! \u00a1No compatible con MAC!<br \/>\n<\/strong><strong>Los lectores est\u00e1n disponibles como lectores individuales o combinados y puedes descargar el software de forma gratuita para programar t\u00fa mismo los lectores para cualquier sistema.<\/strong><br \/>\nT\u00fa eliges para qu\u00e9 sistema queremos programar el lector y te lo entregamos en 1-2 d\u00edas laborables.<\/p>\n<p><em><strong>Este lector es solo para HF y por lo tanto no utiliza selecci\u00f3n de frecuencia.<\/strong><\/em><\/p>\n<p><strong>Para ver qu\u00e9 opci\u00f3n debe elegir en el software para su sistema, utilice nuestra lista de traducciones que puede encontrar en descargas.<\/strong><\/p>\n<p><strong>El lector viene con una garant\u00eda de 2 a\u00f1os.<\/strong><br \/>\nStonehouse Security ha desarrollado el dise\u00f1o y el software para todos los lectores ACCESS, es confiable, r\u00e1pido y adaptado al mercado sueco.<br \/>\nEl lector est\u00e1 adaptado al mercado de la seguridad y sus clientes finales, pero tambi\u00e9n para otras aplicaciones donde es necesario leer el c\u00f3digo del chip electr\u00f3nico en su lector RFID.<br \/>\nLos lectores de sobremesa ACCESS utilizan una conexi\u00f3n USB y son plug and play con lectores ya codificados.<\/p>\n<p>Si necesita ayuda con la programaci\u00f3n, p\u00f3ngase en contacto con nosotros y le ayudaremos de forma gratuita.<br \/>\nEl programa lector maneja: RCO, Bewator\/Vanderbilt de 8 y 13 d\u00edgitos, Axema, Axema VAKA, ASSA, Aptus, Paxton.<\/p>\n<p><strong>\ud83d\udcbe Descarga el software:<\/strong><br \/>\n<a href=\"https:\/\/stonehouse.se\/programvaror\/ACCESS%20-%20Version%201.exe\" rel=\"noopener\">\ud83d\udce5 Versi\u00f3n 1.exe<\/a><br \/>\n<a href=\"https:\/\/stonehouse.se\/programvaror\/ACCESS%20-%20Version%202.exe\" rel=\"noopener\">\ud83d\udce5 Versi\u00f3n 2.exe<\/a><br \/>\n<a href=\"http:\/\/stonehouse.se\/programvaror\/ReaderSetting_Setup_3.0.0.5.exe\" rel=\"noopener\">\ud83d\udce5 Versi\u00f3n 3.0.0.5.exe<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><em><strong>Cable USB incluido.<br \/>\nLo importante es saber qu\u00e9 chip est\u00e1s utilizando al configurar el lector.<\/strong><\/em><\/p>","protected":false},"featured_media":163619,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1743],"product_tag":[2405,2958],"class_list":{"0":"post-54527","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rfid-lasare","7":"product_tag-rel-rfid","8":"product_tag-stonehouse-produkt","9":"product_shipping_class-postnord-varubrev","10":"pa_access-lasare-mifare-mifare-mfd-aptus-9-siffror","11":"pa_access-lasare-mifare-mifare-mfr-axema-vaka-13-siffror","12":"pa_access-lasare-mifare-chippets-uid-kod","13":"pa_access-lasare-mifare-mifare-mfd-assa-10-siffror","14":"pa_access-lasare-mifare-mifare-rco-9-siffror","15":"pa_brands-stonehouse-security","16":"pa_farg-svart","17":"secureus-loop-product","18":"tm-has-options","20":"first","21":"instock","22":"sale","23":"featured","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/54527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/163619"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=54527"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=54527"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=54527"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=54527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}