﻿{"id":56493,"date":"2022-03-11T07:53:00","date_gmt":"2022-03-11T06:53:00","guid":{"rendered":"https:\/\/secureus.se\/produkt\/usb-16gb-gron-med-er-logo\/"},"modified":"2026-03-10T11:30:19","modified_gmt":"2026-03-10T10:30:19","slug":"usb-16gb-gron-med-er-logo","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/usb-16gb-gron-med-er-logo\/","title":{"rendered":"Memoria USB de 16 GB verde \u2013 Logotipo de color gratuito"},"content":{"rendered":"<div>\n<p>Aqu\u00ed tienes memorias USB para tu documentaci\u00f3n o para tus clientes o dentro de la empresa as\u00ed como &quot;regalos&quot;.<\/p>\n<p>Los fabricamos en la f\u00e1brica despu\u00e9s de realizar su pedido y demora entre 14 y 20 d\u00edas h\u00e1biles producirlos despu\u00e9s de realizar el pedido.<\/p>\n<\/div>\n<div>Tenga en cuenta que debe enviarnos su logotipo y, dado que es un elemento de dise\u00f1o, nos comunicaremos con usted con sugerencias de correcci\u00f3n antes de comenzar la producci\u00f3n.<\/div>","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed tienes memorias USB para tu documentaci\u00f3n o para tus clientes o dentro de la empresa as\u00ed como &quot;regalos&quot;. Los fabricamos en la f\u00e1brica despu\u00e9s de realizar su pedido y demora aproximadamente<\/p>","protected":false},"featured_media":144525,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1824],"product_tag":[2918,2958],"class_list":["post-56493","product","type-product","status-publish","has-post-thumbnail","product_cat-usb-minnen-logo-minneskort","product_tag-16-gb","product_tag-stonehouse-produkt","product_shipping_class-postnord-varubrev","pa_brands-stonehouse-security","pa_farg-gron","secureus-loop-product","tm-has-options","first","onbackorder","sale","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/56493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/144525"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=56493"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=56493"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=56493"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=56493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}