{"id":57484,"date":"2022-03-10T14:57:00","date_gmt":"2022-03-10T13:57:00","guid":{"rendered":"https:\/\/secureus.se\/produkt\/2-vags-tradlos-beyond-dual-tech-kband-detektor-inom-utomhus-agililty4-och-wicomm-pro\/"},"modified":"2026-05-12T16:47:44","modified_gmt":"2026-05-12T14:47:44","slug":"risco-rorelsedetektor-med-kamera-2-vags-utomhus-beyond","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/risco-rorelsedetektor-med-kamera-2-vags-utomhus-beyond\/","title":{"rendered":"Detector de movimiento bidireccional para exteriores Risco \u2013 M\u00e1s all\u00e1"},"content":{"rendered":"<h1>Detector de movimiento Risco con c\u00e1mara bidireccional \u2013 Outdoor Beyond<\/h1>\n<p data-start=\"516\" data-end=\"1046\">Detector de movimiento Risco con c\u00e1mara bidireccional Beyond Agility WiComm Pro es una soluci\u00f3n innovadora para la detecci\u00f3n en exteriores y verificaci\u00f3n visual.<\/p>\n<p data-start=\"516\" data-end=\"1046\">Este detector combina tecnolog\u00eda dual con una c\u00e1mara integrada que permite una verificaci\u00f3n visual n\u00edtida a trav\u00e9s de la aplicaci\u00f3n para tel\u00e9fonos inteligentes iRISCO, la interfaz web o la estaci\u00f3n de monitoreo.<\/p>\n<p data-start=\"516\" data-end=\"1046\">Al utilizar dos canales de radio separados con antenas diferentes, se garantiza la transmisi\u00f3n segura tanto de im\u00e1genes como de alarmas, lo que lo hace ideal para su uso en entornos exteriores.<\/p>\n<p data-start=\"1048\" data-end=\"1398\">Beyond utiliza las tecnolog\u00edas de detecci\u00f3n \u00fanicas de RISCO, Sway Recognition\u2122 y Digital Correlation\u2122, para reducir dr\u00e1sticamente las falsas alarmas, lo que hace que esta soluci\u00f3n sea altamente precisa y confiable.<\/p>\n<p data-start=\"1048\" data-end=\"1398\">El detector de movimiento tiene un alcance ajustable de entre 5 y 12 metros y una funci\u00f3n respetuosa con los animales, lo que significa que no reacciona a animales de hasta 50 cm de altura.<\/p>\n<p data-start=\"1400\" data-end=\"1702\">Con una combinaci\u00f3n de sensores infrarrojos y de microondas, Beyond es inmune a la luz solar directa y tiene una funci\u00f3n antienmascaramiento para evitar la manipulaci\u00f3n.<\/p>\n<p data-start=\"1400\" data-end=\"1702\">El detector tambi\u00e9n es f\u00e1cil de instalar en una pared o esquina y ofrece una bater\u00eda de larga duraci\u00f3n (hasta 3 a\u00f1os con bater\u00edas de litio CR123A incluidas).<\/p>\n<p data-start=\"1704\" data-end=\"1872\">Est\u00e1 dise\u00f1ado para funcionar en duras condiciones exteriores, con una temperatura de funcionamiento de -25 \u00b0C a 65 \u00b0C y un nivel de protecci\u00f3n IP65 para soportar las condiciones clim\u00e1ticas.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe title=\"Wicomm Smart Hub EE. UU.\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/5PHoH2dRjEs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Risco Beyond Agility WiComm Pro es un detector de movimiento avanzado con c\u00e1mara integrada para uso en exteriores.<\/p>\n<p>Con dos canales de radio separados y tecnolog\u00eda de detecci\u00f3n que minimiza las falsas alarmas, proporciona una verificaci\u00f3n visual n\u00edtida a trav\u00e9s de la aplicaci\u00f3n del tel\u00e9fono inteligente o la estaci\u00f3n de monitoreo.<\/p>","protected":false},"featured_media":158860,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2731,3191],"product_tag":[3152,2426],"class_list":["post-57484","product","type-product","status-publish","has-post-thumbnail","product_cat-risco-larm","product_cat-utomhusdetektorer","product_tag-cr123-tillbehor","product_tag-rel-risco","pa_risco-produkter-agility-4","pa_wicomm-pro-kategorier-rorelsedetektor","secureus-loop-product","tm-no-options","first","instock","sale","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/57484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/158860"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=57484"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=57484"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=57484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=57484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}