﻿{"id":58459,"date":"2022-10-12T12:13:20","date_gmt":"2022-10-12T10:13:20","guid":{"rendered":"https:\/\/secureus.se\/produkt\/uplus-12v-45-ah\/"},"modified":"2026-04-20T10:32:03","modified_gmt":"2026-04-20T08:32:03","slug":"batteri-12v-45ah","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/batteri-12v-45ah\/","title":{"rendered":"Bater\u00eda UPLUS de 12 V y 45 Ah, versi\u00f3n Pro, para usuarios de 10 a 12 a\u00f1os."},"content":{"rendered":"<h1>Bater\u00eda 12V 45ah \/ Acumulador UPLUS 10-12 A\u00f1os<\/h1>\n<p>UPLUS ofrece una de las gamas m\u00e1s amplias del mercado de bater\u00edas AGM reguladas por v\u00e1lvula con una vida \u00fatil de dise\u00f1o de 10 a 12 a\u00f1os.<\/p>\n<p>Algunos ejemplos de aplicaciones de las bater\u00edas industriales UPLUS son las compuertas de humo, los sistemas de control de acceso y los sistemas de comunicaci\u00f3n en ascensores.<\/p>\n<p>Dimensiones mm (LxAnxAl): 197 x 165 x 170<\/p>\n<p>Peso Kg: 14,50<\/p>\n<p>Bater\u00eda 12V 45ah UPLUS Las bater\u00edas Longlife han sido desarrolladas como una fuente de energ\u00eda donde la alta confiabilidad operativa y la larga vida \u00fatil son necesidades primarias.<\/p>\n<p>Las bater\u00edas se prueban en varias etapas durante el proceso de fabricaci\u00f3n para satisfacer las estrictas demandas que los usuarios del segmento marino imponen a sus bater\u00edas.<\/p>\n<p>La gama UPLUS Marine ofrece bater\u00edas est\u00e1ndar que funcionan excelentemente como bater\u00edas todoterreno y bater\u00edas de ciclo profundo que est\u00e1n dise\u00f1adas para un uso m\u00e1s c\u00edclico.<\/p>\n<p>Por ello, el ciclo profundo es la elecci\u00f3n obvia como bater\u00eda de consumo en sistemas UPS para embarcaciones con muchos consumidores y cargas elevadas.<\/p>\n<p>La mayor\u00eda de los fabricantes de barcos n\u00f3rdicos utilizan UPLUS como est\u00e1ndar, ya que la fiabilidad operativa es lo m\u00e1s importante.<\/p>\n<p>La amplia gama permite encontrar f\u00e1cilmente la bater\u00eda m\u00e1s adecuada para cada instalaci\u00f3n o fuente de alimentaci\u00f3n CC.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bater\u00eda AGM 45 AH 10 -12 a\u00f1os de vida \u00fatil para sistemas de telefon\u00eda, alarma y seguridad.<\/p>","protected":false},"featured_media":142602,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1596,2428,1324],"product_tag":[4406],"class_list":{"0":"post-58459","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ackumulatorer-12v-agm-batterier","7":"product_cat-stromforsorjning-batterier","8":"product_cat-outlet","9":"product_tag-batteri-13-45-ah","10":"product_shipping_class-tunga-paket","11":"pa_brands-uplus","12":"secureus-loop-product","13":"tm-no-options","15":"first","16":"instock","17":"sale","18":"featured","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/58459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/142602"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=58459"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=58459"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=58459"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=58459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}