{"id":72401,"date":"2023-01-23T09:55:48","date_gmt":"2023-01-23T08:55:48","guid":{"rendered":"https:\/\/secureus.se\/produkt\/dsc-neo-power-g-wireless-fjarrkontroll-pg8939-2\/"},"modified":"2026-05-11T15:55:56","modified_gmt":"2026-05-11T13:55:56","slug":"dsc-pg8939-fjarrkontroll","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/dsc-pg8939-fjarrkontroll\/","title":{"rendered":"Transmisor manual de 4 botones DSC PG8939 Transmisor de radio con 4 botones PowerG \u2013 Sistema NEO 868 Mhz"},"content":{"rendered":"<p><strong>DSC PG8939<\/strong> es un control remoto inal\u00e1mbrico avanzado dise\u00f1ado para brindar a los usuarios un control fluido y seguro sobre los sistemas de alarma Iotega, PowerSeries NEO y PRO.<\/p>\n<p>Con sus cuatro botones f\u00e1ciles de usar, los usuarios pueden controlar f\u00e1cilmente varias funciones, incluido activar y desactivar la alarma, as\u00ed como activar las alarmas de emergencia y de p\u00e1nico.<\/p>\n<p>El control remoto est\u00e1 equipado con un retraso \u00fanico de un segundo para cada pulsaci\u00f3n de bot\u00f3n, lo que evita que se active la alarma accidentalmente.<\/p>\n<p>Tambi\u00e9n tiene una confirmaci\u00f3n de estado con indicaci\u00f3n LED y de audio, por lo que los usuarios siempre saben que sus comandos se han ejecutado correctamente.<\/p>\n<p>Con una impresionante duraci\u00f3n de bater\u00eda de hasta 8 a\u00f1os con un uso normal, el DSC PG8939 es pr\u00e1ctico y duradero.<\/p>\n<p>El PG8939 tiene un dise\u00f1o compacto y viene con un clip para cintur\u00f3n y un collar, lo que hace que sea f\u00e1cil tenerlo a mano cuando m\u00e1s lo necesita.<\/p>\n<p>Al integrar el DSC PG8939 con su sistema de seguridad, obtendr\u00e1 una soluci\u00f3n confiable y efectiva para proteger su hogar o negocio.<\/p>\n<p>Esto hace que el DSC PG8939 sea un componente ideal en cualquier sistema de seguridad, combinando conveniencia, confiabilidad y facilidad de uso de la mejor manera posible.<\/p>","protected":false},"excerpt":{"rendered":"<p>El DSC PG8939 es un control remoto inal\u00e1mbrico de cuatro botones que facilita el control de la alarma en los sistemas Iotega, PowerSeries NEO y PRO.<\/p>\n<p>Con una sola pulsaci\u00f3n, los usuarios pueden activar alarmas de emergencia y controlar salidas.<\/p>\n<p>El control remoto tiene una bater\u00eda de larga duraci\u00f3n de hasta 8 a\u00f1os y viene con un LED para confirmaci\u00f3n del estado.<\/p>\n<p>Clip para cintur\u00f3n y collar incluidos para mayor comodidad.<\/p>","protected":false},"featured_media":141654,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3327,1322],"product_tag":[3311,3031],"class_list":["post-72401","product","type-product","status-publish","has-post-thumbnail","product_cat-overfall-fjarrkontrol","product_cat-dsc-larm-neo-power-hybridlarm","product_tag-dsc-neo-svensk-manual","product_tag-neo-ovriga-tillbehor","pa_brands-4dsc","secureus-loop-product","tm-has-options","first","onbackorder","sale","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/72401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/141654"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=72401"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=72401"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=72401"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=72401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}