﻿{"id":91531,"date":"2023-09-27T18:14:11","date_gmt":"2023-09-27T16:14:11","guid":{"rendered":"https:\/\/secureus.se\/elslutbleck-5114-omvand-24v-kolvkontakt\/"},"modified":"2026-07-01T10:23:40","modified_gmt":"2026-07-01T08:23:40","slug":"elslutbleck-5114-omvand-24v-kolvkontakt","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/elslutbleck-5114-omvand-24v-kolvkontakt\/","title":{"rendered":"Cerradura el\u00e9ctrica 5114 Contacto de pist\u00f3n inverso 24 V"},"content":{"rendered":"<h1>Cerradura el\u00e9ctrica 5114 Contacto de pist\u00f3n inverso 24 V<\/h1>\n<p class=\"\" data-start=\"399\" data-end=\"589\">Cerradero el\u00e9ctrico 5114 Reverse 24V con contacto de pist\u00f3n, para puertas con bajos requerimientos de seguridad en comercio, oficinas e industria. Desbloqueado en caso de corte de corriente, resistencia a la rotura 400 kg.<\/p>\n<p class=\"\" data-start=\"625\" data-end=\"1023\">Cerradero El\u00e9ctrico 5114 Contacto de Pist\u00f3n Inverso 24V es un cerradero el\u00e9ctrico perfecto para puertas con bajos requerimientos de seguridad, haci\u00e9ndolo ideal para usar en comercio, oficinas e industria.<\/p>\n<p class=\"\" data-start=\"625\" data-end=\"1023\">Es ideal para cierres internos, donde se requiere un sistema de cierre fiable y rentable pero donde la seguridad no necesita ser tan estricta como en entornos m\u00e1s expuestos.<\/p>\n<p class=\"\" data-start=\"1025\" data-end=\"1532\">Esta cerradura el\u00e9ctrica tiene funci\u00f3n inversa, lo que significa que la puerta se desbloquea en caso de corte de energ\u00eda. Esto lo convierte en una soluci\u00f3n pr\u00e1ctica en situaciones en las que es necesario desbloquear la puerta durante un corte de energ\u00eda.<\/p>\n<p class=\"\" data-start=\"1025\" data-end=\"1532\">La cerradura el\u00e9ctrica est\u00e1 hecha con un pivote de acero y una carcasa de cerradura de aleaci\u00f3n de zinc, lo que lo convierte en un producto robusto y duradero que puede soportar un uso a largo plazo.<\/p>\n<p class=\"\" data-start=\"1025\" data-end=\"1532\">Con una resistencia a la rotura de 4000 N (400 kg), es lo suficientemente fuerte para su uso en muchas puertas que requieren un bloqueo confiable.<\/p>\n<p class=\"\" data-start=\"1534\" data-end=\"1822\">El cerradero el\u00e9ctrico 5114 Reverse 24V con contacto de \u00e9mbolo se puede utilizar en combinaci\u00f3n con cerraduras de pestillo simple o doble, y tambi\u00e9n se puede suministrar con microinterruptor y contacto de \u00e9mbolo de bloqueo, lo que permite integrarlo en un sistema de cierre automatizado o con otras soluciones de seguridad.<\/p>\n<p class=\"\" data-start=\"1824\" data-end=\"1854\">Caracter\u00edsticas y beneficios clave:<\/p>\n<ul data-start=\"1855\" data-end=\"2374\">\n<li class=\"\" data-start=\"1855\" data-end=\"1930\">\n<p class=\"\" data-start=\"1857\" data-end=\"1930\">Funci\u00f3n inversa: se desbloquea en caso de corte de energ\u00eda para un uso flexible.<\/p>\n<\/li>\n<li class=\"\" data-start=\"1931\" data-end=\"2006\">\n<p class=\"\" data-start=\"1933\" data-end=\"2006\">Resistencia a la rotura: Soporta hasta 4000 N (400 kg) para un bloqueo confiable.<\/p>\n<\/li>\n<li class=\"\" data-start=\"2007\" data-end=\"2084\">\n<p class=\"\" data-start=\"2009\" data-end=\"2084\">Barra de torsi\u00f3n de acero: Construcci\u00f3n duradera y resistente al desgaste para una larga vida \u00fatil.<\/p>\n<\/li>\n<li class=\"\" data-start=\"2085\" data-end=\"2163\">\n<p class=\"\" data-start=\"2087\" data-end=\"2163\">Compatibilidad: Adecuado para su uso con cerraduras de una o dos hojas.<\/p>\n<\/li>\n<li class=\"\" data-start=\"2164\" data-end=\"2281\">\n<p class=\"\" data-start=\"2166\" data-end=\"2281\">Se puede suministrar con microinterruptor y contacto de bloqueo del \u00e9mbolo: Para aumentar la flexibilidad y seguridad en la instalaci\u00f3n.<\/p>\n<\/li>\n<li class=\"\" data-start=\"2282\" data-end=\"2374\">\n<p class=\"\" data-start=\"2284\" data-end=\"2374\">No apto para puertas cortafuegos: No apto para uso en puertas cortafuegos.<\/p>\n<\/li>\n<\/ul>\n<p class=\"\" data-start=\"2376\" data-end=\"2405\">Especificaciones t\u00e9cnicas:<\/p>\n<ul data-start=\"2406\" data-end=\"2719\">\n<li class=\"\" data-start=\"2406\" data-end=\"2434\">\n<p class=\"\" data-start=\"2408\" data-end=\"2434\">Voltaje: 24 VCC \u00b110%<\/p>\n<\/li>\n<li class=\"\" data-start=\"2435\" data-end=\"2467\">\n<p class=\"\" data-start=\"2437\" data-end=\"2467\">Consumo de corriente: 0-110 mA<\/p>\n<\/li>\n<li class=\"\" data-start=\"2468\" data-end=\"2510\">\n<p class=\"\" data-start=\"2470\" data-end=\"2510\">Resistencia a la rotura m\u00e1xima: 4000 N (400 kg)<\/p>\n<\/li>\n<li class=\"\" data-start=\"2511\" data-end=\"2531\">\n<p class=\"\" data-start=\"2513\" data-end=\"2531\">Torsi\u00f3n: acero<\/p>\n<\/li>\n<li class=\"\" data-start=\"2532\" data-end=\"2558\">\n<p class=\"\" data-start=\"2534\" data-end=\"2558\">Cuerpo de la cerradura: aleaci\u00f3n de zinc<\/p>\n<\/li>\n<li class=\"\" data-start=\"2559\" data-end=\"2586\">\n<p class=\"\" data-start=\"2561\" data-end=\"2586\">Voltaje de funcionamiento: 24 VCC<\/p>\n<\/li>\n<li class=\"\" data-start=\"2587\" data-end=\"2608\">\n<p class=\"\" data-start=\"2589\" data-end=\"2608\">Contacto del pist\u00f3n: S\u00ed<\/p>\n<\/li>\n<li class=\"\" data-start=\"2609\" data-end=\"2719\">\n<p class=\"\" data-start=\"2611\" data-end=\"2719\">Diodo protector: Se recomienda utilizar un diodo protector cerca de la bobina de disparo el\u00e9ctrico para proteger la electr\u00f3nica.<\/p>\n<\/li>\n<\/ul>\n<div>\n<p>&nbsp;<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<h5><a href=\"https:\/\/elslutblecksguiden.se\/\" target=\"_blank\" rel=\"noopener\">Gu\u00eda para cerraduras el\u00e9ctricas ASSA, cerraduras motorizadas, placas de cierre el\u00e9ctricas y gu\u00eda de reemplazo<\/a><\/h5>","protected":false},"featured_media":139039,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3355],"product_tag":[4197,4201,2967],"class_list":["post-91531","product","type-product","status-publish","has-post-thumbnail","product_cat-elslutbleck","product_tag-24v","product_tag-omvand","product_tag-rg-assa-abloy","product_shipping_class-tunga-paket","pa_brands-abloy","secureus-loop-product","tm-no-options","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/91531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/139039"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=91531"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=91531"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=91531"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=91531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}