﻿{"id":96853,"date":"2024-08-08T21:47:53","date_gmt":"2024-08-08T19:47:53","guid":{"rendered":"https:\/\/secureus.se\/?post_type=product&#038;p=96853"},"modified":"2026-04-23T12:05:34","modified_gmt":"2026-04-23T10:05:34","slug":"handtag-83-rakt-8x53-krom","status":"publish","type":"product","link":"https:\/\/secureus.se\/es\/handtag-83-rakt-8x53-krom\/","title":{"rendered":"Manija de ventana recta 83, 8 x 53, cromada \u2013 Assa Abloy"},"content":{"rendered":"<div>ASSA ABLOY 83 es una manija cl\u00e1sica para ventanas y puertas francesas. El mango tiene pestillos incorporados para posiciones abiertas y cerradas que mantienen el mango en la posici\u00f3n correcta. Disponible en versiones para zurdos, rectos y diestros.<\/div>\n<div><b><br \/>\nCaracter\u00edsticas:<\/b><\/div>\n<div>\n<ul>\n<li>Pestillos incorporados para posiciones abiertas y cerradas que mantienen la manija en la posici\u00f3n correcta.<\/li>\n<li>Pasador fabricado en acero galvanizado cuadrado de 8 mm.<\/li>\n<li>Longitud del pasador: 53 mm<\/li>\n<li>Tornillo recomendado: TKFX 4,0 mm.<\/li>\n<li>Accesorios: Cerradura de manija Fix 840 y 850.<\/li>\n<li>El acoplamiento de manija, 833, 833\/16 se utiliza cuando las manijas se deben montar en ambos lados.<\/li>\n<li>Material: Metal zamak<\/li>\n<li>Tratamiento superficial: cromado<\/li>\n<\/ul>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>ASSA ABLOY 83 es una manija cl\u00e1sica para ventanas y puertas francesas. El mango tiene pestillos incorporados para posiciones abiertas y cerradas que mantienen el mango en la posici\u00f3n correcta. Disponible en versiones para zurdos, rectos y<\/p>","protected":false},"featured_media":136616,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4126,4127],"product_tag":[],"class_list":{"0":"post-96853","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fonsterhandtag","7":"product_cat-handtag-altandorr","8":"product_shipping_class-postnord-varubrev","9":"pa_brands-abloy","10":"secureus-loop-product","11":"tm-no-options","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product\/96853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media\/136616"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/media?parent=96853"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_brand?post=96853"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_cat?post=96853"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/es\/wp-json\/wp\/v2\/product_tag?post=96853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}