﻿{"id":52272,"date":"2022-06-28T13:18:11","date_gmt":"2022-06-28T11:18:11","guid":{"rendered":"https:\/\/secureus.se\/produkt\/dekal-anvand-ej-hissen\/"},"modified":"2026-04-23T11:14:17","modified_gmt":"2026-04-23T09:14:17","slug":"dekal-anvand-ej-hissen","status":"publish","type":"product","link":"https:\/\/secureus.se\/fi\/dekal-anvand-ej-hissen\/","title":{"rendered":"Tarra \u00c4l\u00e4 k\u00e4yt\u00e4 hissi\u00e4"},"content":{"rendered":"<p>Tarra 105\u00d7148 mm &quot;\u00c4l\u00e4 k\u00e4yt\u00e4 hissi\u00e4&quot;<\/p>","protected":false},"excerpt":{"rendered":"<p>Tarra 105\u00d7148 mm &quot;\u00c4l\u00e4 k\u00e4yt\u00e4 hissi\u00e4&quot;<\/p>","protected":false},"featured_media":143204,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1559],"product_tag":[],"class_list":{"0":"post-52272","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anvisningsskyltar-brandskydd","7":"product_shipping_class-postnord-varubrev","8":"secureus-loop-product","9":"tm-no-options","11":"first","12":"outofstock","13":"sale","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/product\/52272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/media\/143204"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/media?parent=52272"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/product_brand?post=52272"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/product_cat?post=52272"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fi\/wp-json\/wp\/v2\/product_tag?post=52272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}