﻿{"id":142169,"date":"2022-07-04T10:19:27","date_gmt":"2022-07-04T08:19:27","guid":{"rendered":"https:\/\/secureus.se\/monteringsstolpe-sa30t-15\/"},"modified":"2026-01-12T13:11:08","modified_gmt":"2026-01-12T12:11:08","slug":"monteringsstolpe-sa30t-15","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/monteringsstolpe-sa30t-15\/","title":{"rendered":"Poteau de montage Safetron SA30T-15"},"content":{"rendered":"<p>Poteau de montage coud\u00e9 en inox pour plaques d&#039;extr\u00e9mit\u00e9 \u00e9lectriques SAFETRON de la s\u00e9rie standard : ES17 \/ ES19. Adapt\u00e9 aux cadres en bois et en m\u00e9tal, utilis\u00e9 avec des serrures \u00e0 double ou simple chute du type connect\/evolution ou module. <\/p>\n<p>\u2022 \u00c9quivalent \u00e0 ST 4003-15<br \/>\n<br \/>\n\u2022 Taille de la langue\u00a0: 15\u00a0mm<br \/>\n<br \/>\n\u2022 Dimensions\u00a0: (hxlxp) 245x40x15 mm<\/p>","protected":false},"excerpt":{"rendered":"<p>Poteau de montage coud\u00e9 en acier inoxydable pour g\u00e2ches \u00e9lectriques SAFETRON de la s\u00e9rie standard : ES17 \/ ES19. Adapt\u00e9 aux cadres en bois et en m\u00e9tal, utilis\u00e9 avec des serrures \u00e0 double ou simple p\u00eane de type connect\/evolution ou module. \u2022<\/p>","protected":false},"featured_media":142168,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4735],"product_tag":[4440,4866],"class_list":{"0":"post-142169","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-monteringsstolpe","7":"product_tag-safetron-montagestolpar-es17-es19-sa-modell","8":"product_tag-safetron-20","9":"product_shipping_class-tunga-paket","10":"pa_brands-7safetron","11":"secureus-loop-product","12":"tm-no-options","14":"first","15":"instock","16":"featured","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/142169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/142168"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=142169"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=142169"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=142169"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=142169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}