﻿{"id":142344,"date":"2022-07-04T10:46:09","date_gmt":"2022-07-04T08:46:09","guid":{"rendered":"https:\/\/secureus.se\/monteringsstolpe-sa31-17\/"},"modified":"2026-01-12T13:13:55","modified_gmt":"2026-01-12T12:13:55","slug":"monteringsstolpe-sa31-17","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/monteringsstolpe-sa31-17\/","title":{"rendered":"Poteau de montage Safetron SA31-17"},"content":{"rendered":"<p>Poteau de montage plat en inox pour plaques d&#039;extr\u00e9mit\u00e9 \u00e9lectriques SAFETRON de la s\u00e9rie standard : ES17 \/ ES19. Adapt\u00e9 aux cadres en bois et en m\u00e9tal, utilis\u00e9 avec des serrures \u00e0 double ou simple chute du type connect\/evolution ou module. <\/p>\n<p>\u2022 \u00c9quivalent \u00e0 ST 4001-17<br \/>\n<br \/>\n\u2022 Taille de la langue\u00a0: 17\u00a0mm<br \/>\n<br \/>\n\u2022 Dimensions\u00a0: (hxl) 245\u00d742 mm<\/p>","protected":false},"excerpt":{"rendered":"<p>Poteau de montage plat en acier inoxydable pour g\u00e2ches \u00e9lectriques SAFETRON de la s\u00e9rie standard : ES17 \/ ES19. Adapt\u00e9 aux cadres en bois et en m\u00e9tal, utilis\u00e9 avec des serrures \u00e0 double ou simple p\u00eane de type connect\/evolution ou module. \u2022<\/p>","protected":false},"featured_media":142343,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4735],"product_tag":[4440,4866],"class_list":{"0":"post-142344","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-monteringsstolpe","7":"product_tag-safetron-montagestolpar-es17-es19-sa-modell","8":"product_tag-safetron-20","9":"product_shipping_class-tunga-paket","10":"pa_brands-7safetron","11":"secureus-loop-product","12":"tm-no-options","14":"first","15":"instock","16":"sale","17":"featured","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/142344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/142343"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=142344"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=142344"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=142344"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=142344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}