{"id":142353,"date":"2022-07-04T10:37:12","date_gmt":"2022-07-04T08:37:12","guid":{"rendered":"https:\/\/secureus.se\/monteringsstolpe-sa45\/"},"modified":"2026-01-12T13:15:22","modified_gmt":"2026-01-12T12:15:22","slug":"monteringsstolpe-sa45","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/monteringsstolpe-sa45\/","title":{"rendered":"Poteau de montage Safetron SA45"},"content":{"rendered":"<p>Poteau de montage plat en inox pour plaques d&#039;extr\u00e9mit\u00e9 \u00e9lectriques SAFETRON de la s\u00e9rie standard : ES17 \/ ES19. Adapt\u00e9 au syst\u00e8me de profil\u00e9s SCH\u00dcCO ADS 50.NI, utilis\u00e9 avec des serrures \u00e0 double ou simple battant du type connect\/evolution ou module.<\/p>\n<p>\u2022 Adapt\u00e9 pour SCH\u00dcCO ADS 50.NI<br \/>\n<br \/>\n\u2022 \u00c9quivalent au ST 4040<br \/>\n<br \/>\n\u2022 Taille de la langue\u00a0: 8\u00a0mm<br \/>\n<br \/>\n\u2022 Dimensions\u00a0: (hxl) 245\u00d734,3 mm<\/p>","protected":false},"excerpt":{"rendered":"<p>Poteau de montage plat en inox pour plaques d&#039;extr\u00e9mit\u00e9 \u00e9lectriques SAFETRON de la s\u00e9rie standard : ES17 \/ ES19. Adapt\u00e9 au syst\u00e8me de profil\u00e9s SCH\u00dcCO ADS 50.NI, utilis\u00e9 avec des serrures \u00e0 double ou simple battant du type connect\/evolution ou module.<\/p>","protected":false},"featured_media":142352,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4735],"product_tag":[4440,4866],"class_list":["post-142353","product","type-product","status-publish","has-post-thumbnail","product_cat-monteringsstolpe","product_tag-safetron-montagestolpar-es17-es19-sa-modell","product_tag-safetron-20","pa_brands-7safetron","secureus-loop-product","tm-no-options","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/142353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/142352"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=142353"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=142353"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=142353"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=142353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}