{"id":160302,"date":"2025-11-21T11:15:46","date_gmt":"2025-11-21T10:15:46","guid":{"rendered":"https:\/\/secureus.se\/ateco-vd-6297-100-kapslad-varmedetektor-varmedetektor-100-grader\/"},"modified":"2026-08-26T21:59:08","modified_gmt":"2026-08-26T19:59:08","slug":"ateco-vd-6297-100-kapslad-varmedetektor-varmedetektor-100-grader","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/ateco-vd-6297-100-kapslad-varmedetektor-varmedetektor-100-grader\/","title":{"rendered":"D\u00e9tecteur de chaleur Ateco VD-6297-100 (bo\u00eetier ferm\u00e9), temp\u00e9rature de 100 degr\u00e9s."},"content":{"rendered":"<div class=\"headernamehrnone\">Le 6297 est un d\u00e9tecteur de chaleur conventionnel ferm\u00e9 \u00e0 protection maximale (IP67). Son capteur thermique est de type bim\u00e9tallique. Les d\u00e9tecteurs sont \u00e9quip\u00e9s d&#039;une indication LED (sauf sur le mod\u00e8le 120\u00b0) et d&#039;une sortie pour indication suppl\u00e9mentaire. Ils sont fournis avec 3 presse-\u00e9toupes. Les d\u00e9tecteurs de la s\u00e9rie 629X sont insensibles \u00e0 la polarit\u00e9. Le d\u00e9tecteur est fourni avec 3 r\u00e9ducteurs pour presse-\u00e9toupes, adapt\u00e9s aux c\u00e2bles de 3 \u00e0 10 mm de diam\u00e8tre. Le filetage du raccord \u00e0 vis est PF \u00bd&quot;. La polarit\u00e9 de la sortie E est toujours conforme au marquage, quelle que soit la polarit\u00e9 des connexions A et B. Les d\u00e9tecteurs sont certifi\u00e9s CPD et DoP.<\/div>\n<div><\/div>\n<div class=\"row headername\">\n<div class=\"item-header rd-hyg-item-header\"><strong>Principales caract\u00e9ristiques<\/strong><\/div>\n<div class=\"row\">\n<ul>\n<li>D\u00e9tecteur de chaleur encapsul\u00e9 avec seuil de 100 degr\u00e9s<\/li>\n<li>Capteur de chaleur bim\u00e9tallique pour une d\u00e9tection fiable<\/li>\n<li>Indice de protection IP67 contre la poussi\u00e8re et l&#039;eau<\/li>\n<li>Dot\u00e9 d&#039;un indicateur LED et d&#039;une alimentation suppl\u00e9mentaire<\/li>\n<li>Contient 3 presse-\u00e9toupes et 3 r\u00e9ducteurs pour diff\u00e9rentes tailles de c\u00e2bles<\/li>\n<li>Ind\u00e9pendant de la polarit\u00e9 pour une installation facile<\/li>\n<li>Certifi\u00e9 conforme aux normes CPD et DoP<\/li>\n<\/ul>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<ul class=\"UnorderedListStyle--1koui9a ksyVRL mainfeatureslist\">\n<li class=\"ListItemStyle--1yqofwy kEFzCE\">D\u00e9tecteur de chaleur encapsul\u00e9 avec seuil de 100 degr\u00e9s<\/li>\n<li class=\"ListItemStyle--1yqofwy kEFzCE\">Capteur de chaleur bim\u00e9tallique pour une d\u00e9tection fiable<\/li>\n<li class=\"ListItemStyle--1yqofwy kEFzCE\">Indice de protection IP67 contre la poussi\u00e8re et l&#039;eau<\/li>\n<\/ul>","protected":false},"featured_media":160301,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4157],"product_tag":[],"class_list":["post-160302","product","type-product","status-publish","has-post-thumbnail","product_cat-varmedetektor","pa_brands-ateco","pa_farg-vit","secureus-loop-product","tm-no-options","first","onbackorder","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/160302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/160301"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=160302"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=160302"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=160302"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=160302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}