﻿{"id":52095,"date":"2022-06-29T13:09:42","date_gmt":"2022-06-29T11:09:42","guid":{"rendered":"https:\/\/secureus.se\/produkt\/vaggsignering-bricka\/"},"modified":"2026-02-20T11:53:53","modified_gmt":"2026-02-20T10:53:53","slug":"vaggsignering-bricka","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/vaggsignering-bricka\/","title":{"rendered":"Plateau de signalisation mural"},"content":{"rendered":"<p>Convient, par exemple, au marquage de borniers, de bo\u00eetes de jonction, de d\u00e9tecteurs, de contacts magn\u00e9tiques, d&#039;alimentations \u00e9lectriques, etc. o\u00f9 un marquage ou une identification est souhait\u00e9. Se fixe soit avec des vis, soit avec un tampon de fixation adh\u00e9sif (non inclus).<\/p>","protected":false},"excerpt":{"rendered":"<p>Convient, par exemple, au marquage de borniers, de bo\u00eetes de jonction, de d\u00e9tecteurs, de contacts magn\u00e9tiques, d&#039;alimentations \u00e9lectriques, etc. o\u00f9 un marquage ou une identification est souhait\u00e9. Se fixe soit avec des vis, soit avec un tampon de fixation adh\u00e9sif (non inclus).<\/p>","protected":false},"featured_media":142296,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1547],"product_tag":[2211],"class_list":{"0":"post-52095","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-plint-larm-telebox","7":"product_tag-box-tillbehor","8":"product_shipping_class-postnord-varubrev","9":"pa_brands-alarmtech","10":"secureus-loop-product","11":"tm-no-options","13":"first","14":"outofstock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/52095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/142296"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=52095"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=52095"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=52095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=52095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}