{"id":53561,"date":"2022-06-21T18:15:39","date_gmt":"2022-06-21T16:15:39","guid":{"rendered":"https:\/\/secureus.se\/produkt\/fargo-45615-ymckoko-half-panel-colour-ribbon-500-prints\/"},"modified":"2026-08-27T01:20:26","modified_gmt":"2026-08-26T23:20:26","slug":"ribbon-fargo-45615-ymckoko-half-panel-colour-ribbon-500-prints","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/ribbon-fargo-45615-ymckoko-half-panel-colour-ribbon-500-prints\/","title":{"rendered":"Ruban demi-panneau Fargo 45615 YMCKOKO (500 impressions)"},"content":{"rendered":"<h1>Ruban<br \/>\n  Fargo \u2013 45615 (500 impressions)<\/h1>\n<p>Fargo Ribbon \u2013 45615 (500 impressions) est un ruban pour<br \/>\n  impression de cartes plastiques aux couleurs vives, texte clair et de bonne qualit\u00e9<br \/>\n  Reproduction d\u00e9taill\u00e9e. Le ruban YMCKOK assure la combinaison correcte de panneaux de couleur et<br \/>\n  Couche de protection pour l&#039;impression professionnelle de cartes.<\/p>\n<p>Convient aux cartes d&#039;identit\u00e9, cartes d&#039;acc\u00e8s, cartes de membre et autres.<br \/>\n  cartes plastiques pour lesquelles une qualit\u00e9 d&#039;impression et une fiabilit\u00e9 \u00e9lev\u00e9es sont importantes.<\/p>\n<ul>\n<li>Capacit\u00e9 : jusqu&#039;\u00e0 500 impressions<\/li>\n<li>Type de groupe : YMCKOK<\/li>\n<li>Convient \u00e0 l&#039;impression de cartes recto verso<\/li>\n<li>Num\u00e9ro d&#039;article : 45615<\/li>\n<\/ul>\n<p><strong>Compatible avec Fargo<br \/>\n  DTC1500.<\/strong><\/p>\n<p><strong>Poids du produit :<\/strong> 0,35kg<\/p>","protected":false},"excerpt":{"rendered":"<p>Ruban couleur \u2013 Ruban \u2013 Retransfert vers imprimante de cartes et imprimante de cartes plastiques<\/p>","protected":false},"featured_media":143747,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3214,4843],"product_tag":[3201,4863,2921,3069],"class_list":["post-53561","product","type-product","status-publish","has-post-thumbnail","product_cat-fargo-fargband-retransfer","product_cat-dtc1500-band","product_tag-fargo-tillbehor","product_tag-pf","product_tag-ribbon-ymck-farg","product_tag-trade-produkt","pa_brands-fargo","pa_fargband-kortskrivare-fargo","secureus-loop-product","tm-has-options","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/53561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/143747"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=53561"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=53561"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=53561"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=53561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}