﻿{"id":57202,"date":"2022-03-10T15:27:00","date_gmt":"2022-03-10T14:27:00","guid":{"rendered":"https:\/\/secureus.se\/produkt\/ensidig-eko-serie-id-korthallare-staende-for-cr80-kort-100-pack-farg-orange\/"},"modified":"2025-12-31T19:37:15","modified_gmt":"2025-12-31T18:37:15","slug":"ensidig-eko-serie-id-korthallare-staende-for-cr80-kort-100-pack-farg-orange","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/ensidig-eko-serie-id-korthallare-staende-for-cr80-kort-100-pack-farg-orange\/","title":{"rendered":"Porte-cartes pour cartes d&#039;acc\u00e8s \/ cartes d&#039;identit\u00e9 \u2013 Eko BioBadge CR80 Vertical, simple face, orange (paquet de 100)"},"content":{"rendered":"<p>Notre nouvelle gamme de porte-cartes d&#039;identit\u00e9 simple face \u00e9cologiquement d\u00e9gradables, fabriqu\u00e9s en plastique biod\u00e9gradable.<\/p>\n<p>Ces titulaires de cartes jouent un r\u00f4le important en nous aidant tous \u00e0 r\u00e9duire notre empreinte carbone.<\/p>\n<p>La conception des bords moul\u00e9s r\u00e9duit le stress sur les cartes et les fissures, ce qui entra\u00eene moins d&#039;\u00e9missions de cartes, ce qui permet \u00e0 vos clients d&#039;\u00e9conomiser du temps et de l&#039;argent.<\/p>\n<p>86 mm x 54 mm<\/p>\n<p>Convient au format de cr\u00e9dit standard CR80<\/p>\n<p>Vendu en paquet de 100<\/p>","protected":false},"excerpt":{"rendered":"<p>Notre nouvelle gamme de porte-cartes d&#039;identit\u00e9 biod\u00e9gradables \u00e0 simple face, fabriqu\u00e9s en plastique biod\u00e9gradable, joue un r\u00f4le important en nous aidant tous \u00e0 r\u00e9duire notre empreinte carbone.<\/p>","protected":false},"featured_media":145628,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[4888,1667],"product_tag":[2851],"class_list":{"0":"post-57202","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-enkelsidig-staende-korthallare","7":"product_cat-korthallare-passerkort-idkort","8":"product_tag-korthallare-staende-eko","9":"product_shipping_class-tunga-paket","10":"pa_brands-stonehouse-security","11":"pa_farg-orange","12":"pa_rfid-tillbehor-korthallare","13":"secureus-loop-product","14":"tm-no-options","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/57202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/145628"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=57202"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=57202"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=57202"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=57202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}