﻿{"id":81767,"date":"2022-11-28T13:13:15","date_gmt":"2022-11-28T12:13:15","guid":{"rendered":"https:\/\/secureus.se\/produkt\/monteringsfaste-magnetkontakt-svart\/"},"modified":"2026-07-14T15:03:18","modified_gmt":"2026-07-14T13:03:18","slug":"ajax-smart-bracket-monteringsfaste-dorrsensor-magnetkontakt-2","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/ajax-smart-bracket-monteringsfaste-dorrsensor-magnetkontakt-2\/","title":{"rendered":"Ajax Reservdel \u2013 Monteringsf\u00e4ste till DoorProtect \/ GlassProtect (Endast Sensor, inte magnet) \u2013 Svart"},"content":{"rendered":"<h3><strong>Ajax Smart Bracket Monteringsf\u00e4ste f\u00f6r D\u00f6rrsensor, Glaskross, Magnetkontakt &#8211; DoorProtect samt GlassProtect<\/strong><\/h3>\n<p>L&#039;Ajax Smart Bracket est un support de montage efficace et convivial con\u00e7u pour faciliter l&#039;installation des capteurs de porte et des contacts magn\u00e9tiques Ajax.<\/p>\n<p>Ce support de montage permet de fixer rapidement et facilement les capteurs sur des surfaces verticales ou dans les coins, optimisant ainsi la couverture et garantissant un fonctionnement fiable de votre syst\u00e8me de s\u00e9curit\u00e9 Ajax.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ajax Smart Bracket \u00e4r ett monteringsf\u00e4ste designat f\u00f6r Ajax d\u00f6rrsensorer, glaskross och magnetkontakter.<\/p>\n<p><strong>Partie<\/strong> till DoorProtect, DoorProtect Plus och GlassProtect<\/p>\n<p><strong>Note<\/strong>Ce support est destin\u00e9 \u00e0 la partie capteur elle-m\u00eame (capteur de porte\/fen\u00eatre), et non \u00e0 la partie magn\u00e9tique.<\/p>","protected":false},"featured_media":168164,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3128],"product_tag":[],"class_list":["post-81767","product","type-product","status-publish","has-post-thumbnail","product_cat-ajax-reservdelar-fasten","product_shipping_class-postnord-varubrev","pa_brands-ajax-systems","pa_color-svart","pa_farg-svart","secureus-loop-product","tm-no-options","first","instock","sale","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/81767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/168164"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=81767"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=81767"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=81767"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=81767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}