{"id":83124,"date":"2023-09-13T15:39:05","date_gmt":"2023-09-13T13:39:05","guid":{"rendered":"https:\/\/secureus.se\/?post_type=product&#038;p=83124"},"modified":"2026-08-26T22:06:35","modified_gmt":"2026-08-26T20:06:35","slug":"or-parm-vit-vikt-a3-a4","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/or-parm-vit-vikt-a3-a4\/","title":{"rendered":"OU Classeur BLANC POIDS A3\/A4"},"content":{"rendered":"<p>Classeur OR blanc adapt\u00e9 aux feuilles A3\/A4 pli\u00e9es avec recto et verso transparents.<\/p>","protected":false},"excerpt":{"rendered":"<p>Classeur OR blanc adapt\u00e9 aux feuilles A3\/A4 pli\u00e9es avec recto et verso transparents.<\/p>","protected":false},"featured_media":139833,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2950],"product_tag":[],"class_list":["post-83124","product","type-product","status-publish","has-post-thumbnail","product_cat-or-skap-sakerhet","pa_brands-viewtech","secureus-loop-product","tm-no-options","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/83124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/139833"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=83124"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=83124"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=83124"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=83124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}