﻿{"id":89272,"date":"2024-01-04T15:43:19","date_gmt":"2024-01-04T14:43:19","guid":{"rendered":"https:\/\/secureus.se\/produkt\/fonsterbroms-160-3-oppning-91-180-hoger\/"},"modified":"2026-05-05T16:10:44","modified_gmt":"2026-05-05T14:10:44","slug":"fonsterbroms-dorrbroms-160-3-oppning-91-180-hoger","status":"publish","type":"product","link":"https:\/\/secureus.se\/fr\/fonsterbroms-dorrbroms-160-3-oppning-91-180-hoger\/","title":{"rendered":"ASSA Fix 160\/3 Frein de vitre \/ Frein de porte \u2013 Droit \u2013 347 mm \u2013 Ouverture 91\u2013180\u00b0"},"content":{"rendered":"<p><strong>ASSA Fix 160\/3<\/strong> est un <strong>frein de fen\u00eatre pour fen\u00eatres et portes-fen\u00eatres<\/strong> qui est utilis\u00e9 conjointement avec <strong>ASSA\/FIX espagnolette avec transfert<\/strong>Le frein permet \u00e0 la porte ou \u00e0 la fen\u00eatre de rester en position d&#039;a\u00e9ration ouverte au lieu de se fermer brutalement ou de s&#039;ouvrir compl\u00e8tement.<\/p>\n<p>Elle est actionn\u00e9e par la poign\u00e9e de la cr\u00e9mone et cr\u00e9e une friction dans la tige de frein afin de maintenir la porte dans la position souhait\u00e9e.<\/p>\n<p>Mod\u00e8le <strong>160<\/strong> a <strong>support de cadre amovible<\/strong> et est mont\u00e9 avec le support de cadre <strong>5580<\/strong> ou <strong>5550T<\/strong> qui sont achet\u00e9s s\u00e9par\u00e9ment.<\/p>\n<h3>Caract\u00e9ristiques<\/h3>\n<ul>\n<li>Support de cadre amovible (les mod\u00e8les 150 et 150S ont un support fixe)<\/li>\n<li>Utilis\u00e9 avec l&#039;espagnolette ASSA\/FIX \u00e0 transfert<\/li>\n<li>Convient aux fen\u00eatres et aux portes-fen\u00eatres<\/li>\n<li>Actionn\u00e9 par la poign\u00e9e \u00e0 cr\u00e9mone<\/li>\n<li>Maintient la porte en position de ventilation<\/li>\n<li>Glisse en cas de surcharge pour prot\u00e9ger les charni\u00e8res et les ferrures<\/li>\n<li>jeu libre en position de poign\u00e9e ouverte<\/li>\n<li>La friction de maintien augmente avec un angle d&#039;ouverture plus grand<\/li>\n<\/ul>\n<h3>Dimensions \u2013 ASSA Fix 160\/3 Ouverture 91\u2013180\u00b0<\/h3>\n<ul>\n<li>Pour une largeur d&#039;arc : 420\u2013717 mm (selon l&#039;angle d&#039;ouverture, voir sch\u00e9ma)<\/li>\n<li>Longueur de l&#039;arbre de serrure : 656 mm (coup\u00e9 par le client)<\/li>\n<li>Longueur du bo\u00eetier de frein : 347 mm<\/li>\n<\/ul>\n<h3>Important concernant la gauche et la droite<\/h3>\n<p>Le nom <strong>gauche ou droite<\/strong> Cela n&#039;a rien \u00e0 voir avec le fait que la porte s&#039;ouvre \u00e0 gauche ou \u00e0 droite.<br \/>\nLa variante est en revanche d\u00e9termin\u00e9e par <strong>la position du levier de frein \u00e0 l&#039;int\u00e9rieur du bo\u00eetier de frein<\/strong>.<\/p>\n<p>\u2022 Levier de frein \u00e0 gauche = mod\u00e8le pour gaucher<br \/>\n\u2022 Levier de frein \u00e0 droite = mod\u00e8le pour droitier<\/p>\n<p>Lors de cette v\u00e9rification, tenez le bo\u00eetier de frein avec l&#039;ouverture orient\u00e9e vers le haut et le c\u00f4t\u00e9 court face \u00e0 vous.<\/p>\n<div style=\"background: #f6f8fa;padding: 14px;border-radius: 6px;margin: 18px 0\">\n<p><strong>Vous ne savez pas quel mod\u00e8le choisir ?<\/strong><br \/>\nComparez votre syst\u00e8me de freinage actuel avec les images du produit ou consultez la gamme compl\u00e8te.<a style=\"font-weight: bold\" href=\"https:\/\/secureus.se\/fr\/fonsterbroms\/\"><br \/>\nVoir tous les freins de fen\u00eatre ici \u2192<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"background: #f6f8fa;padding: 14px;border-radius: 6px;margin: 15px 0\">\n<p><strong>\u2714 Ce mod\u00e8le est BON<\/strong><\/p>\n<p>\nVeuillez v\u00e9rifier votre frein de vitre existant avant de passer commande.<br \/>\nV\u00e9rifiez \u00e9galement cela <strong>longueur et support du bo\u00eetier de frein<\/strong> compatible avec votre syst\u00e8me de freinage existant.\n<\/p>\n<p>\nPour v\u00e9rifier droite\/gauche\u00a0: commencez par <strong>bas du bo\u00eetier de frein<\/strong> et imaginez que <strong>Le b\u00e2ton est point\u00e9 dans la direction oppos\u00e9e \u00e0 vous.<\/strong>.<br \/>\nEnsuite, examinez le bo\u00eetier de frein.\n<\/p>\n<p>\nLors de l&#039;achat de ce mod\u00e8le, <strong>La goupille de frein se trouve du c\u00f4t\u00e9 droit.<\/strong>.\n<\/p>\n<p>\n<strong>C\u00f4t\u00e9 gauche = mod\u00e8le gauche<\/strong><br \/>\n<strong>C\u00f4t\u00e9 droit = mod\u00e8le droit<\/strong>\n<\/p>\n<p>\n<strong>Conseils si le frein est install\u00e9\u00a0:<\/strong><br \/>\nRegardez le bo\u00eetier de frein par le bas et imaginez que le levier pointe dans la direction oppos\u00e9e \u00e0 vous.\n<\/p>\n<p style=\"margin-bottom: 0\">\n<strong>Important :<\/strong> Ne regardez pas dans la direction du manche, sinon la gauche et la droite seront invers\u00e9es.\n<\/p>\n<p><img decoding=\"async\" style=\"max-width: 300px;width: 100%;margin-top: 12px;border-radius: 6px\" src=\"https:\/\/secureus.se\/wp-content\/uploads\/2026\/03\/hoger-vanster-enkel.jpg\" alt=\"Guide de frein de fen\u00eatre gauche ou droite\" \/><\/p>\n<\/div>","protected":false},"featured_media":139593,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3126,4794],"product_tag":[4100,4803,4102,4863],"class_list":{"0":"post-89272","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fonsterbroms","7":"product_cat-assa-fix-160","8":"product_tag-4100","9":"product_tag-347mm","10":"product_tag-hoger","11":"product_tag-pf","12":"product_shipping_class-tunga-paket","13":"pa_brands-abloy","14":"secureus-loop-product","15":"tm-no-options","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product\/89272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media\/139593"}],"wp:attachment":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/media?parent=89272"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_brand?post=89272"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat?post=89272"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_tag?post=89272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}