﻿{"id":5067,"count":3,"description":"<h2 data-section-id=\"1bvokmn\" data-start=\"149\" data-end=\"204\">SecureX \u2013 Claviers et RFID pour une gestion d&#039;alarme fluide<\/h2>\r\n<p data-start=\"206\" data-end=\"439\">Vous trouverez ici des claviers, des t\u00e9l\u00e9commandes et des solutions RFID pour une gestion simple et s\u00e9curis\u00e9e de votre syst\u00e8me d&#039;alarme SecureX. Gr\u00e2ce aux accessoires adapt\u00e9s, vous pouvez armer, d\u00e9sarmer ou activer les fonctions d&#039;urgence rapidement, sans avoir \u00e0 utiliser votre t\u00e9l\u00e9phone portable.<\/p>\r\n<p data-start=\"441\" data-end=\"596\">Les claviers et les dispositifs RFID rendent le syst\u00e8me encore plus convivial, notamment dans les foyers avec plusieurs utilisateurs ou dans les entreprises o\u00f9 diff\u00e9rentes personnes ont besoin d&#039;y acc\u00e9der. <!--more--><\/p>\r\n\r\n<h3 data-section-id=\"96kpay\" data-start=\"611\" data-end=\"658\">Contr\u00f4le flexible \u2013 choisissez ce qui vous convient<\/h3>\r\n<p data-start=\"660\" data-end=\"814\">Que vous souhaitiez une t\u00e9l\u00e9commande discr\u00e8te dans votre poche, un clavier mural \u00e0 l&#039;entr\u00e9e ou des \u00e9tiquettes RFID pour un acc\u00e8s rapide, la solution est l\u00e0.<\/p>\r\n<p data-start=\"816\" data-end=\"852\">Vous y trouverez notamment :<\/p>\r\n<p data-start=\"854\" data-end=\"988\">\u2022 <a href=\"https:\/\/secureus.se\/fr\/securex-quickcontrol-larmstyrning-med-sos-knapp\/\">SecureX QuickControl \u2013 contr\u00f4le facile de l&#039;alarme avec bouton SOS<\/a><br data-start=\"912\" data-end=\"915\" \/>Une t\u00e9l\u00e9commande compacte \u00e0 activation rapide et fonction d&#039;urgence int\u00e9gr\u00e9e.<\/p>\r\n<p data-start=\"990\" data-end=\"1103\">\u2022 <a href=\"https:\/\/secureus.se\/fr\/securex-rfid-tagg-for-larmstyrning\/\">\u00c9tiquette RFID SecureX pour la commande d&#039;alarme<\/a><br data-start=\"1026\" data-end=\"1029\" \/>Identification simple et facile pour un armement et un d\u00e9sarmement rapides de l&#039;alarme.<\/p>\r\n<p data-start=\"1105\" data-end=\"1255\">\u2022 <a href=\"https:\/\/secureus.se\/fr\/securex-keyaccess-knappsats-rfid\/\">Clavier SecureX KeyAccess avec RFID longue port\u00e9e (500 m\u00e8tres)<\/a><br data-start=\"1166\" data-end=\"1169\" \/>Clavier professionnel longue port\u00e9e pour entr\u00e9es, commerces et grandes propri\u00e9t\u00e9s.<\/p>\r\n\r\n\r\n<hr data-start=\"1257\" data-end=\"1260\" \/>\r\n\r\n<h3 data-section-id=\"1kbsktk\" data-start=\"1262\" data-end=\"1296\">Communication s\u00e9curis\u00e9e et stable<\/h3>\r\n<p data-start=\"1298\" data-end=\"1492\">Tous les claviers et dispositifs RFID communiquent via la technologie radio longue port\u00e9e et stable du syst\u00e8me SecureX. Ceci garantit une r\u00e9ponse rapide, une grande fiabilit\u00e9 op\u00e9rationnelle et une utilisation s\u00e9curis\u00e9e, m\u00eame dans les grands b\u00e2timents.<\/p>\r\n\r\n<h3 data-section-id=\"18esdou\" data-start=\"1494\" data-end=\"1525\">Parfait pour la maison et l&#039;entreprise<\/h3>\r\n<p data-start=\"1527\" data-end=\"1566\">Les claviers num\u00e9riques sont particuli\u00e8rement utiles lorsque\u00a0:<\/p>\r\n<p data-start=\"1568\" data-end=\"1734\">\u2022 Plusieurs membres de la famille utilisent l&#039;alarme<br data-start=\"1608\" data-end=\"1611\" \/>\u2022 Le personnel a besoin d&#039;acc\u00e9der aux entreprises<br data-start=\"1648\" data-end=\"1651\" \/>\u2022 Vous souhaitez un contr\u00f4le rapide \u00e0 l&#039;entr\u00e9e<br data-start=\"1688\" data-end=\"1691\" \/>\u2022 Vous souhaitez une commande physique de l&#039;alarme sans application<\/p>\r\n<p data-start=\"1736\" data-end=\"1811\">Le syst\u00e8me peut facilement \u00eatre \u00e9tendu avec davantage d&#039;utilisateurs et de tags si n\u00e9cessaire.<\/p>\r\n\r\n\r\n<hr data-start=\"1813\" data-end=\"1816\" \/>\r\n\r\n<h3 data-section-id=\"z6y39n\" data-start=\"1818\" data-end=\"1866\">Contr\u00f4le d&#039;alarme fluide, s\u00e9curis\u00e9 et professionnel<\/h3>\r\n<p data-start=\"1868\" data-end=\"1999\">Avec les claviers SecureX et les accessoires RFID, vous b\u00e9n\u00e9ficiez d&#039;une solution flexible qui simplifie votre quotidien sans compromettre la s\u00e9curit\u00e9.<\/p>","link":"https:\/\/secureus.se\/fr\/securex-knappsatser\/","name":"SecureX - Claviers","slug":"securex-knappsatser","taxonomy":"product_cat","parent":5059,"meta":[],"menu_order":168,"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat\/5067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product_cat\/5059"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/fr\/wp-json\/wp\/v2\/product?product_cat=5067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}