﻿{"id":3190,"count":4,"description":"<div class=\"term-description\">\r\n\r\nRisco-sirenes zijn volledig compatibel met LightSYS Air (V6) en WiComm Pro (V5) en gedeeltelijk met Agility (V2\u2013V4).\r\n\r\n<\/div>","link":"https:\/\/secureus.se\/nl\/sirener-risco-larm\/","name":"Sirenes","slug":"sirener-risco-larm","taxonomy":"product_cat","parent":2731,"meta":[],"menu_order":203,"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat\/3190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat\/2731"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product?product_cat=3190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}