﻿{"id":3330,"count":6,"description":"","link":"https:\/\/secureus.se\/nl\/powerseries-1616-1864\/","name":"DSC Power-serie 1616 - 1864","slug":"powerseries-1616-1864","taxonomy":"product_cat","parent":1318,"meta":[],"menu_order":245,"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat\/3330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat\/1318"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product?product_cat=3330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}