﻿{"id":3977,"count":12,"description":"","link":"https:\/\/secureus.se\/nl\/or-skap-brand-brandskydd\/","name":"OF Kastbrand","slug":"or-skap-brand-brandskydd","taxonomy":"product_cat","parent":2903,"meta":[],"menu_order":319,"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat\/3977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product_cat\/2903"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/nl\/wp-json\/wp\/v2\/product?product_cat=3977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}