﻿{"id":4186,"count":3,"description":"","link":"https:\/\/secureus.se\/no\/skaplas-industrilas\/","name":"Skapl\u00e5s \/ Industril\u00e5s","slug":"skaplas-industrilas","taxonomy":"product_cat","parent":4185,"meta":[],"menu_order":422,"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product_cat\/4186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product_cat\/4185"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product?product_cat=4186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}