﻿{"id":4955,"count":3,"description":"","link":"https:\/\/secureus.se\/no\/axis-varmekameror\/","name":"Axis varmebildekameraer","slug":"axis-varmekameror","taxonomy":"product_cat","parent":4948,"meta":[],"menu_order":354,"acf":[],"_links":{"self":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product_cat\/4955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product_cat\/4948"}],"wp:post_type":[{"href":"https:\/\/secureus.se\/no\/wp-json\/wp\/v2\/product?product_cat=4955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}